{"id":2735,"date":"2021-11-01T15:30:00","date_gmt":"2021-11-01T12:30:00","guid":{"rendered":"https:\/\/chocolette.com\/principale\/"},"modified":"2026-04-10T16:34:55","modified_gmt":"2026-04-10T13:34:55","slug":"principale","status":"publish","type":"page","link":"https:\/\/chocolette.com\/fr\/principale\/","title":{"rendered":"principale"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2735\" class=\"elementor elementor-2735\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-q_id=\"#whyred\" class=\"elementor-section elementor-top-section elementor-element elementor-element-7ed2bf3c elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"7ed2bf3c\" data-element_type=\"section\" data-e-type=\"section\" id=\"section1\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-59f75ac1\" data-id=\"59f75ac1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-367072dc elementor-widget elementor-widget-heading\" data-id=\"367072dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LA PREMI\u00c8RE<div class=\"thin\">DANS<\/div>LE MONDE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd94097 elementor-widget elementor-widget-text-editor\" data-id=\"fd94097\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les barres de chocolat ROUGE ont \u00e9t\u00e9 judicieusement<\/p>\n<p>con\u00e7u pour sublimer vos papilles afin que vous puissiez<\/p>\n<p><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif;\">profiter pleinement de la saveur de chaque bouch\u00e9e.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b9978ef\" data-id=\"b9978ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ef0b223 elementor-widget__width-inherit elementor--h-position-center elementor--v-position-middle elementor-widget elementor-widget-slides\" data-id=\"1ef0b223\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;none&quot;,&quot;transition&quot;:&quot;fade&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\" dir=\"ltr\" data-animation=\"fadeInRight\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-db3c901 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"1diapositive\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-a2813d6 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"2diapositive\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-77d05f0 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"3diapositive\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-462b86c elementor-section-content-middle elementor-reverse-mobile elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"462b86c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4864656b\" data-id=\"4864656b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7061092b elementor-invisible elementor-widget elementor-widget-image\" data-id=\"7061092b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1070\" height=\"709\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/almond.jpg\" class=\"attachment-full size-full wp-image-2226\" alt=\"\" srcset=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/almond.jpg 1070w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/almond-300x199.jpg 300w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/almond-1024x679.jpg 1024w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/almond-768x509.jpg 768w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/almond-700x464.jpg 700w\" sizes=\"(max-width: 1070px) 100vw, 1070px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6fb33ef9\" data-id=\"6fb33ef9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b53e237 elementor-widget elementor-widget-image\" data-id=\"1b53e237\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2020\/11\/heart.png\" title=\"c\u0153ur\" alt=\"c\u0153ur\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46739ae0 elementor-widget elementor-widget-heading\" data-id=\"46739ae0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00c9LICIEUX<div>&amp;<\/div><div>L\u00c9GER<\/div><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d05f875 elementor-widget elementor-widget-text-editor\" data-id=\"d05f875\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cr\u00e9\u00e9 par des Ma\u00eetres Chocolatiers de France<\/p>\n<p>et la Suisse, notre style unique et brevet\u00e9 cr\u00e9e<\/p>\n<p>un bon chocolat sans sucre ajout\u00e9 et <\/p>\n<p>jusqu&#8217;\u00e0 la moiti\u00e9 de la mati\u00e8re grasse des autres chocolats. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14ac1068 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"14ac1068\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f59f267\" data-id=\"3f59f267\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e418345 elementor-section-content-top elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"2e418345\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6288f953\" data-id=\"6288f953\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b920c95 elementor-widget elementor-widget-image\" data-id=\"7b920c95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2020\/11\/heart.png\" title=\"c\u0153ur\" alt=\"c\u0153ur\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23417b5d elementor-widget elementor-widget-heading\" data-id=\"23417b5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TOUT LE PLAISIR<div class=\"thin\">RIEN<\/div>de LA CULPABILIT\u00c9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ee56505 elementor-widget elementor-widget-text-editor\" data-id=\"6ee56505\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>RED Dark Chocolette est le premier chocolat de la<\/p>\n<p><span style=\"font-family: Circe, sans-serif;\">monde&nbsp;<\/span><span style=\"font-family: Circe, sans-serif;\">contenant jusqu&#8217;\u00e0 la moiti\u00e9 des calories des autres Dark&nbsp;<\/span><\/p>\n<p><span style=\"font-family: Circe, sans-serif;\">des chocolats.<\/span>&nbsp; <span style=\"font-family: Circe, sans-serif;\">RED a \u00e9t\u00e9 cr\u00e9\u00e9 sans ajout<\/span><\/p>\n<p>sucre transform\u00e9 qui nous donne notre go\u00fbt incroyable<\/p>\n<p>&nbsp;avec une quantit\u00e9 r\u00e9duite de graisse. &nbsp;<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1ee1c74\" data-id=\"1ee1c74\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f77af44 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"6f77af44\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1070\" height=\"709\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/extra.jpg\" class=\"attachment-full size-full wp-image-1925\" alt=\"\" srcset=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/extra.jpg 1070w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/extra-300x199.jpg 300w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/extra-1024x679.jpg 1024w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/extra-768x509.jpg 768w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/extra-700x464.jpg 700w\" sizes=\"(max-width: 1070px) 100vw, 1070px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-q_id=\"#ingredients\" class=\"elementor-section elementor-top-section elementor-element elementor-element-74c8e71d elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"74c8e71d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2fcd40e8\" data-id=\"2fcd40e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-646d73ee elementor-widget elementor-widget-heading\" data-id=\"646d73ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">INGR\u00c9DIENTS<div class=\"thin\">DANS NOTRE<\/div>CHOCOLAT<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4dbde936\" data-id=\"4dbde936\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12926f11 elementor-widget elementor-widget-text-editor\" data-id=\"12926f11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Notre recette est bas\u00e9e sur des produits naturels de cacao <\/p>\n<p>livr\u00e9 de C\u00f4te d&#8217;Ivoire (C\u00f4te d&#8217;Ivoire), <\/p>\n<p>l&#8217;\u00e9rythritol et le maltitol sont des \u00e9dulcorants naturels s\u00fbrs, <\/p>\n<p>polydextrose riche en fibres alimentaires.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c734052 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"5c734052\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-25cf47b2\" data-id=\"25cf47b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f49d297 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"2f49d297\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1070\" height=\"709\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/coffee.jpg\" class=\"attachment-full size-full wp-image-1953\" alt=\"\" srcset=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/coffee.jpg 1070w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/coffee-300x199.jpg 300w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/coffee-1024x679.jpg 1024w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/coffee-768x509.jpg 768w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/coffee-700x464.jpg 700w\" sizes=\"(max-width: 1070px) 100vw, 1070px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fd8dd50 elementor-widget elementor-widget-spacer\" data-id=\"1fd8dd50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-30c726ea\" data-id=\"30c726ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42fb9f08 elementor-widget elementor-widget-heading\" data-id=\"42fb9f08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"thin\">QUEL EST NOTRE CHOCOLAT<br>FAIT \u00c0 PARTIR DE?<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f50d068 elementor-widget elementor-widget-text-editor\" data-id=\"2f50d068\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les produits de cacao de qualit\u00e9 sont au c\u0153ur du Chocolat Rouge. Nous utilisons des produits \u00e0 base de cacao des meilleurs fournisseurs de C\u00f4te d&#8217;Ivoire. Notre mission est de produire un chocolat savoureux et sain, et nous ne ferons aucun compromis l\u00e0-dessus&nbsp;!<br \/>\n<br \/>\nNos fournisseurs poss\u00e8dent leurs propres fermes de cacao et ils maintiennent les normes les plus \u00e9lev\u00e9es lors de la s\u00e9lection, de la torr\u00e9faction et du broyage des f\u00e8ves de cacao. L&#8217;objectif est de lib\u00e9rer les notes gustatives et aromatiques les plus d\u00e9licates tout en s&#8217;assurant que le go\u00fbt final est riche et plein.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d927031 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"1d927031\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-21f326a5\" data-id=\"21f326a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-146c0bec elementor-widget elementor-widget-heading\" data-id=\"146c0bec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SOURCES NATURELLES<br><div class=\"thin\">DE LA DOUCEUR<span style=\"font-family: Circe, sans-serif\"><\/span><\/div><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-145aa8d3\" data-id=\"145aa8d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17b75cf6 elementor-widget elementor-widget-image\" data-id=\"17b75cf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" title=\"cocoa\" alt=\"cocoa\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f0af832 elementor-widget elementor-widget-image\" data-id=\"5f0af832\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/100quality.png\" title=\"100qualit\u00e9\" alt=\"100qualit\u00e9\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dc444d4 rose elementor-widget elementor-widget-text-editor\" data-id=\"4dc444d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le meilleur de la C\u00f4te d&#8217;Ivoire<\/p>\n<p>&nbsp;les f\u00e8ves de cacao donnent \u00e0 notre chocolat son<\/p>\n<p>&nbsp;saveur signature<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78d39b0d elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"78d39b0d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5f113541\" data-id=\"5f113541\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20aa7c30 elementor-widget elementor-widget-image\" data-id=\"20aa7c30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/melon.png\" title=\"melon\" alt=\"melon\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50948d14 rose elementor-widget elementor-widget-text-editor\" data-id=\"50948d14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Polydextrose &#8211; une source riche<\/p>\n<p>de fibres alimentaires \u00e0 base de<\/p>\n<p>ingr\u00e9dients aide \u00e0 garder notre chocolat<\/p>\n<p>soucieux de leur sant\u00e9.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-51442f15\" data-id=\"51442f15\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6100a6fe elementor-widget elementor-widget-image\" data-id=\"6100a6fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/praline1.png\" title=\"pralin\u00e91\" alt=\"pralin\u00e91\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1c9035c8\" data-id=\"1c9035c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54e99521 elementor-widget elementor-widget-image\" data-id=\"54e99521\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" title=\"leaf\" alt=\"leaf\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a70a930 rose elementor-widget elementor-widget-text-editor\" data-id=\"5a70a930\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un v\u00e9g\u00e9tal z\u00e9ro calorie<br \/>\u00e9dulcorant \u00e9rythritol, \u00e9galement connu<br \/>comme le \u00ab sucre melon \u00bb rehausse<br \/>la douceur de notre chocolat<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d628095 elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"7d628095\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-40c2fc17\" data-id=\"40c2fc17\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3358235 elementor-widget elementor-widget-image\" data-id=\"3358235\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cook.png\" title=\"cuisiner\" alt=\"cuisiner\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54069b65 rose elementor-widget elementor-widget-text-editor\" data-id=\"54069b65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le traitement unique<br \/>de mati\u00e8res premi\u00e8res nous permet de cr\u00e9er le go\u00fbt parfait.<br \/>Nous fabriquons notre chocolat \u00e0 une temp\u00e9rature de 55\u00baC<br \/>(au lieu de 80\u00b0C normal).<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7847bc16\" data-id=\"7847bc16\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-725c3f8e elementor-widget elementor-widget-image\" data-id=\"725c3f8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/diamond.png\" title=\"diamant\" alt=\"diamant\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f3fdb0 rose elementor-widget elementor-widget-text-editor\" data-id=\"3f3fdb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La forme unique du diamant<br \/>de chocolat et pralines<br \/>permettre aux r\u00e9cepteurs de percevoir parfaitement<br \/>go\u00fbt ouvert de chocolat<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-q_id=\"#discover\" class=\"elementor-section elementor-top-section elementor-element elementor-element-55e8f40a elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"55e8f40a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7153bb2b\" data-id=\"7153bb2b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f790e25 elementor-widget elementor-widget-slider_revolution\" data-id=\"3f790e25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"slider_revolution.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"wp-block-themepunch-revslider\">\n\t\t\t<!-- START Products REVOLUTION SLIDER 6.7.40 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_1_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_1_1\" style=\"\" data-version=\"6.7.40\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-169\" data-title=\"Extra\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2020\/12\/UK_EXD_CMYK_01.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\" class=\"extra\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Extra\" title=\"coffee\" width=\"1013\" height=\"782\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-bg=\"p:60% 50%;f:auto;\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-169-layer-0\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,46px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-169-layer-3\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:775px,640px,486px,10px;yo:225px,185px,140px,240px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-169-layer-4\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-bsh=\"c:#000000;v:10px,8px,6px,3px;b:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,15px;yo:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:230px,189px,143px,40%;h:500px,412px,313px,auto;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:extra_old;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1080\" height=\"2347\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/04\/PENAL_EU_EXTRA_DARK_100g_FRONT-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-169-layer-5\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:69px,56px,42px,27px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,22;l:90,74,56,34;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>CHOCOLAT NOIR \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-169-layer-11\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:141px,116px,88px,61px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:24,19,14,14;l:24,19,14,16;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;h:auto,auto,auto,36px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;font-family:'Circe';\"\n\t\t\t\t\t\t\t>EXTRA \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-169-layer-12\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:172px,142px,107px,102px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>383 kcal \/ 100 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-169-layer-14\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:319px,263px,199px,50px;yo:390px,322px,244px,290px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:110px,90px,68px,87px;h:110px,90px,68px,87px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:590;sp:600;sR:590;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7810;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:17;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"191\" height=\"191\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/60cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-169-layer-63\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:255px,210px,159px,17px;yo:11px,9px,6px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-169-layer-64\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:244px,201px,152px,335px;yo:224px,184px,139px,128px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:142px,117px,88px,88px;h:53px,43px,32px,53px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:18;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"237\" height=\"88\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/03\/21_3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-169-layer-112\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:788px,650px,493px,10px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:164px,135px,102px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:extra_old;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>PLUS D'INFOS \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-170\" data-title=\"Dark\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2020\/12\/UK_DS_CMYK_01.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Dark\" title=\"principale\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-170-layer-22\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:788px,650px,493px,15px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:164px,135px,102px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:extra_old-1;ms:rs-24;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>PLUS D'INFOS \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-170-layer-60\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:69px,56px,42px,27px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,22;l:90,74,56,34;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>CHOCOLAT NOIR \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-170-layer-81\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:255px,210px,159px,17px;yo:11px,9px,6px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-170-layer-86\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:244px,201px,152px,335px;yo:210px,173px,131px,128px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:142px,117px,88px,88px;h:53px,43px,32px,53px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"237\" height=\"88\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/03\/21_3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-170-layer-141\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:172px,142px,107px,102px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>373 kcal \/ 100 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-170-layer-146\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,46px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-170-layer-147\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:775px,640px,486px,10px;yo:225px,185px,140px,240px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-170-layer-148\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-bsh=\"c:#000000;v:10px,8px,6px,3px;b:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,15px;yo:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:230px,189px,143px,40%;h:500px,412px,313px,auto;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:extra_old-1;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1080\" height=\"2347\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/04\/PENAL_EU_DARK_100g_FRONT-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-171\" data-title=\"Orange\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2020\/12\/UK_OA_CMYK_01.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Orange\" title=\"principale\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-171-layer-71\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:395px,326px,247px,73px;yo:451px,372px,282px,380px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:90px,74px,56px,55px;h:97px,80px,60px,59px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:600;sp:600;sR:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7800;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:18;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"158\" height=\"170\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/almond-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-171-layer-72\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:285px,235px,178px,27px;yo:303px,250px,189px,258px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:166px,137px,104px,117px;h:202px,166px,126px,142px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:610;sp:600;sR:610;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7790;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:19;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"269\" height=\"327\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/orange.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-171-layer-88\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:255px,210px,159px,16px;yo:11px,9px,6px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-171-layer-89\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:244px,201px,152px,335px;yo:210px,173px,131px,191px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:142px,117px,88px,88px;h:53px,43px,32px,53px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:17;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"237\" height=\"88\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/03\/21_3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-171-layer-110\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:788px,650px,493px,15px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:163px,134px,101px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:dark-n-1;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>PLUS D'INFOS \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-171-layer-149\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:45px,37px,28px,27px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,22;l:45,37,28,30;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>ORANGE ET <br \/>\nAMANDES \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-171-layer-150\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:141px,116px,88px,123px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:24,19,14,14;l:24,19,14,16;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;h:auto,auto,auto,36px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;font-family:'Circe';\"\n\t\t\t\t\t\t\t>CHOCOLAT NOIR \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-171-layer-151\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:172px,142px,107px,164px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>378 kcal \/ 100 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-171-layer-152\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,46px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-171-layer-153\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:775px,640px,486px,10px;yo:225px,185px,140px,240px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-171-layer-154\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-bsh=\"c:#000000;v:10px,8px,6px,3px;b:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:-4px,-3px,-2px,15px;yo:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:230px,189px,143px,40%;h:500px,412px,313px,auto;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:dark-n-1;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1080\" height=\"2347\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/04\/PENAL_EU_DARK_OA_100g_FRONT-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-172\" data-title=\"Milk\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2020\/12\/UK_MS_CMYK_01.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Milk\" title=\"principale\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-172-layer-70\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:255px,210px,159px,-10px;yo:244px,201px,152px,153px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:278px,229px,173px,206px;h:328px,270px,205px,243px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:590;sp:600;sR:590;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7810;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"483\" height=\"570\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/milk.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-172-layer-76\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-325px,-268px,-203px,353px;yo:71px,58px,44px,22px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,22;l:90,74,56,34;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>CHOCOLAT AU LAIT \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-172-layer-91\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:255px,210px,159px,17px;yo:11px,9px,6px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-172-layer-95\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:244px,201px,152px,335px;yo:210px,173px,131px,128px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:142px,117px,88px,88px;h:51px,42px,31px,53px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:17;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"240\" height=\"87\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/03\/22_2.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-172-layer-115\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:788px,650px,493px,15px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:165px,136px,103px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:dark-n-11;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>PLUS D'INFOS \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-172-layer-157\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:172px,142px,107px,102px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>393 kcal \/ 100 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-172-layer-158\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,46px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-172-layer-159\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:775px,640px,486px,10px;yo:225px,185px,140px,240px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-172-layer-160\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-bsh=\"c:#000000;v:10px,8px,6px,3px;b:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,15px;yo:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:230px,189px,143px,40%;h:500px,412px,313px,auto;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:dark-n-11;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1080\" height=\"2347\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/01\/PENAL_NEW_3D-UK-MILK-TEMPLATE-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-173\" data-title=\"Apple\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2020\/12\/UK_AM_CMYK_01.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Apple\" title=\"principale\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-173-layer-68\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:298px,246px,186px,20px;yo:284px,234px,177px,258px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:178px,146px,110px,140px;h:190px,156px,118px,149px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:600;sp:600;sR:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7800;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:18;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"327\" height=\"349\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/apple.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-173-layer-69\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:400px,330px,250px,85px;yo:441px,364px,276px,387px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:68px,56px,42px,47px;h:58px,47px,35px,40px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:590;sp:600;sR:590;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7810;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:19;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"120\" height=\"102\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/macadamia1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-173-layer-96\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:244px,201px,152px,335px;yo:210px,173px,131px,191px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:142px,117px,88px,88px;h:52px,42px,31px,53px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:17;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"240\" height=\"88\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/03\/19_2.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-173-layer-98\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:255px,210px,159px,17px;yo:11px,9px,6px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-173-layer-120\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:788px,650px,493px,15px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:163px,134px,101px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:oa-n-1;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>PLUS D'INFOS \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-173-layer-161\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-296px,-244px,-185px,335px;yo:43px,35px,26px,27px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,22;l:45,37,28,30;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,119px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>POMME ET <br \/>\nNOISETTES \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-173-layer-162\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:141px,116px,88px,123px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:24,19,14,14;l:24,19,14,16;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;h:auto,auto,auto,36px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;font-family:'Circe';\"\n\t\t\t\t\t\t\t>CHOCOLAT AU LAIT \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-173-layer-163\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:172px,142px,107px,164px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>400 kcal \/ 100 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-173-layer-164\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-bsh=\"c:#000000;v:10px,8px,6px,3px;b:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,15px;yo:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:230px,189px,143px,40%;h:500px,412px,313px,auto;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:oa-n-1;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1080\" height=\"2347\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/01\/PENAL_NEW_3D-UK-\u0410_H-TEMPLATE-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-173-layer-165\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,46px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-173-layer-166\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:775px,640px,486px,10px;yo:225px,185px,140px,240px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-174\" data-title=\"Macadamia\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2020\/12\/UK_HM_CMYK_01.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Macadamia\" title=\"principale\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-174-layer-67\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:318px,262px,199px,40px;yo:314px,259px,196px,261px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:154px,127px,96px,115px;h:176px,145px,110px,131px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:600;sp:600;sR:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7800;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:18;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"273\" height=\"312\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/hazelnut.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-174-layer-100\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:255px,210px,159px,17px;yo:11px,9px,6px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-174-layer-102\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:244px,201px,152px,335px;yo:210px,173px,131px,191px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:142px,117px,88px,88px;h:51px,42px,31px,53px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:17;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"240\" height=\"87\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/03\/22_2.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-174-layer-127\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:788px,650px,493px,15px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:163px,134px,101px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:apple-n-1;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>PLUS D'INFOS \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-174-layer-167\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:45px,37px,28px,27px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:32,26,19,22;l:45,37,28,30;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,138px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>NOISETTES ET <br \/>\nNOIX DE MACADAMIA \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-174-layer-168\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:141px,116px,88px,123px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:24,19,14,14;l:24,19,14,16;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;h:auto,auto,auto,36px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;font-family:'Circe';\"\n\t\t\t\t\t\t\t>CHOCOLAT AU LAIT \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-174-layer-169\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:172px,142px,107px,164px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>403 kcal \/ 100 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-174-layer-170\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-bsh=\"c:#000000;v:10px,8px,6px,3px;b:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,15px;yo:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:230px,189px,143px,40%;h:500px,412px,313px,auto;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:apple-n-1;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1080\" height=\"2347\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/01\/PENAL_NEW_3D-UK-HM-TEMPLATE-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-174-layer-171\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,46px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-174-layer-172\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:775px,640px,486px,10px;yo:225px,185px,140px,240px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-176\" data-title=\"Pralines\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/milk-candy.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Pralines\" title=\"principale\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-176-layer-18\" \n\t\t\t\t\t\t\t\tclass=\"box\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,35px;y:m;yo:-80px,-70px,-65px,-140px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:528px,425px,322px,322px;h:470px,378px,287px,287px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:nutfil-n-1;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"772\" height=\"687\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/pralines.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-176-layer-25\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:202px,166px,126px,17px;yo:45px,37px,28px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:799px,659px,500px,462px;h:667px,550px,417px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-176-layer-73\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:220px,181px,137px,350px;yo:302px,249px,189px,192px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:176px,145px,110px,85px;h:70px,57px,43px,34px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:600;sp:600;sR:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7800;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:19;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"304\" height=\"121\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/praline.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-176-layer-134\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:842px,695px,528px,15px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:161px,132px,100px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:nutfil-n-1;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>PLUS D'INFOS \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-176-layer-179\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,365px;yo:69px,56px,42px,26px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,22;l:90,74,56,30;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,110px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>FOURR\u00c9 AUX NOIX \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-176-layer-180\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,365px;yo:141px,116px,88px,92px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:24,19,14,14;l:24,19,14,16;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;h:auto,auto,auto,36px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;font-family:'Circe';\"\n\t\t\t\t\t\t\t>PRALINES AU LAIT \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-176-layer-181\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,365px;yo:172px,142px,107px,133px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>428 kcal \/ 100 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-176-layer-183\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-176-layer-184\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:571px,471px,357px,227px;yo:25px,20px,15px,320px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-176-layer-185\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:365px,301px,228px,38px;yo:491px,405px,307px,276px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:139px,114px,86px,91px;h:113px,93px,70px,74px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:nutfil-n-1;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:590;sp:600;sR:590;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7810;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:18;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"218\" height=\"177\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/macadamia.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-177\" data-title=\"Coconut\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/coconut.jpg\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Coconut\" title=\"principale\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-177-layer-9\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:571px,471px,357px,227px;yo:25px,20px,15px,320px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-177-layer-30\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:842px,695px,528px,15px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:165px,136px,103px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:pralines-nut-n-1;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>PLUS D'INFOS \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-177-layer-42\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:202px,166px,126px,17px;yo:45px,37px,28px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:799px,659px,500px,462px;h:667px,550px,417px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-177-layer-85\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:304px,251px,190px,43px;yo:440px,363px,275px,259px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:220px,181px,137px,125px;h:217px,179px,135px,123px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:600;sp:600;sR:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7800;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"405\" height=\"400\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/coco1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-177-layer-186\" \n\t\t\t\t\t\t\t\tclass=\"box\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,35px;y:m;yo:-80px,-70px,-65px,-140px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:528px,425px,322px,322px;h:470px,378px,287px,286px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:pralines-nut-n-1;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"776\" height=\"690\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/coconut.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-177-layer-188\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-177-layer-189\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:220px,181px,137px,350px;yo:302px,249px,189px,192px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:176px,145px,110px,85px;h:70px,57px,43px,34px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:600;sp:600;sR:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7800;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:19;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"304\" height=\"121\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/praline.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-177-layer-191\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,365px;yo:172px,142px,107px,133px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:233px,192px,145px,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>405 kcal \/ 100 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-177-layer-192\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,365px;yo:141px,116px,88px,92px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:24,19,14,14;l:24,19,14,16;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;h:auto,auto,auto,36px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;font-family:'Circe';\"\n\t\t\t\t\t\t\t>PRALINES AU LAIT \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-177-layer-193\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,365px;yo:45px,37px,28px,26px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,22;l:45,37,28,30;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,110px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>FOURR\u00c9 \u00c0 LA NOIX <br \/>\nDE COCO \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-178\" data-title=\"Dark Bar\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/darkbar1.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Dark Bar\" title=\"principale\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-178-layer-38\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:842px,695px,528px,15px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:165px,136px,103px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:dark-n-12;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>PLUS D'INFOS \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-178-layer-51\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:230px,189px,143px,17px;yo:74px,61px,46px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-178-layer-78\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:45px,37px,28px,26px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,22;l:45,37,28,30;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,110px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>CHOCOLAT <br \/>\nNOIR \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-178-layer-136\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,8px;y:m;yo:-85px,-70px,-55px,-110px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:500px,412px,313px,313px;h:284px,234px,177px,178px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:dark-n-12;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"600\" height=\"341\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/01\/Chocolate-Bars_NEW-3d-UK_DARK-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-178-layer-196\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-178-layer-199\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:172px,142px,107px,133px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>100 kcal \/ 26 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-178-layer-209\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:498px,411px,312px,180px;yo:69px,56px,42px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-179\" data-title=\"Orange Bar\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/orangebar1.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Orange Bar\" title=\"principale\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-179-layer-6\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:498px,411px,312px,180px;yo:69px,56px,42px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-179-layer-54\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:842px,695px,528px,15px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:166px,137px,104px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:oa-n-11;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>PLUS D'INFOS \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-179-layer-107\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:567px,468px,355px,192px;yo:455px,375px,284px,305px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:90px,74px,56px,53px;h:97px,80px,60px,57px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:600;sp:600;sR:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7800;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:17;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"158\" height=\"170\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/almond-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-179-layer-108\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:671px,554px,420px,250px;yo:397px,327px,248px,283px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:166px,137px,104px,107px;h:202px,166px,126px,130px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:610;sp:600;sR:610;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7790;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:18;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"269\" height=\"327\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/orange.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-179-layer-138\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:230px,189px,143px,17px;yo:74px,61px,46px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-179-layer-202\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:141px,116px,88px,118px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:24,19,14,14;l:24,19,14,16;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;h:auto,auto,auto,36px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;font-family:'Circe';\"\n\t\t\t\t\t\t\t>CHOCOLAT NOIR \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-179-layer-203\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:172px,142px,107px,159px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>100 kcal \/ 26 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-179-layer-205\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-179-layer-207\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,8px;y:m;yo:-85px,-70px,-55px,-110px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:500px,412px,313px,313px;h:284px,234px,177px,178px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:oa-n-11;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"600\" height=\"341\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/01\/Chocolate-Bars_NEW-3d-UK_DARK_OA-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-179-layer-208\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:45px,37px,28px,26px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,22;l:45,37,28,30;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,110px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>ORANGE ET <br \/>\nAMANDES \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-180\" data-title=\"Milk Bar\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/milkbar1.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Milk Bar\" title=\"principale\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-180-layer-7\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:498px,411px,312px,180px;yo:69px,56px,42px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-180-layer-46\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:842px,695px,528px,15px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:163px,134px,101px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:milk-n-1;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>PLUS D'INFOS \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-180-layer-79\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:45px,37px,28px,26px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,22;l:45,37,28,30;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,110px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>CHOCOLAT <br \/>\nAU LAIT \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-180-layer-140\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:230px,189px,143px,17px;yo:74px,61px,46px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-180-layer-211\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:172px,142px,107px,133px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>100 kcal \/ 26 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-180-layer-213\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-180-layer-215\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,8px;y:m;yo:-85px,-70px,-55px,-110px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:500px,412px,313px,313px;h:284px,234px,177px,178px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:milk-n-1;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"600\" height=\"341\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/01\/Chocolate-Bars_NEW-3d-UK_MILK-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-181\" data-title=\"Milk HM\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/orangebar1.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Milk HM\" title=\"principale\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-181-layer-8\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:498px,411px,312px,180px;yo:69px,56px,42px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-181-layer-122\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:842px,695px,528px,352px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:161px,132px,100px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:hm-n-11;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>PLUS D'INFOS \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-181-layer-137\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:665px,549px,417px,278px;yo:374px,308px,234px,258px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:154px,127px,96px,107px;h:176px,145px,110px,122px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:600;sp:600;sR:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7800;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:18;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"273\" height=\"312\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/hazelnut.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-181-layer-142\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:230px,189px,143px,17px;yo:74px,61px,46px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-181-layer-217\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:45px,37px,28px,26px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,22;l:45,37,28,30;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,148px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>NOISETTES ET <br \/>\nNOIX DE MACADAMIA \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-181-layer-218\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:141px,116px,88px,118px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:24,19,14,14;l:24,19,14,16;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;h:auto,auto,auto,36px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;font-family:'Circe';\"\n\t\t\t\t\t\t\t>CHOCOLAT AU LAIT \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-181-layer-219\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:172px,142px,107px,159px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>105 kcal \/ 26 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-181-layer-221\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-181-layer-222\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,8px;y:m;yo:-85px,-70px,-55px,-110px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:500px,412px,313px,313px;h:284px,234px,177px,178px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:hm-n-11;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"600\" height=\"341\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/01\/Chocolate-Bars_NEW-3d-UK_MILK_HM-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t\t<rs-static-layers><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-1-layer-1\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer-static\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:r;xo:120px,99px,75px,0;y:m;yo:-90px,-90px,-70px,-115px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:57px,47px,46px,46px;h:62px,51px,50px,50px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:jumptoslide;slide:next;'\n\t\t\t\t\t\t\t\tdata-btrans=\"rY:180;\"\n\t\t\t\t\t\t\t\tdata-onslides=\"s:1;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;cursor:pointer;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"76\" height=\"83\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2020\/11\/arrow.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-1-layer-2\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer-static\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:120px,99px,75px,0;y:m;yo:-90px,-90px,-70px,-115px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:57px,47px,46px,46px;h:62px,51px,50px,50px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:jumptoslide;slide:previous;'\n\t\t\t\t\t\t\t\tdata-onslides=\"s:1;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;cursor:pointer;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"76\" height=\"83\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2020\/11\/arrow.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\t\t\t\t\t--><\/rs-static-layers>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_1_1',rl:[1240,1024,778,480],el:[880,800,760,760],gw:[1240,1024,778,480],gh:[880,800,760,760],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider11\"]!==undefined) {window.RS_MODULES.modules[\"revslider11\"].once = false;window.revapi1 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b960356 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"2b960356\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-377fd7b8\" data-id=\"377fd7b8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a7b8ad2 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"5a7b8ad2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-5c0704e3\" data-id=\"5c0704e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-1a0d8c3a\" data-id=\"1a0d8c3a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3763ee6c uael-video-gallery__column-1 uael-video-gallery-tablet__column-1 uael-video-gallery-mobile__column-1 elementor-widget elementor-widget-uael-video-gallery\" data-id=\"3763ee6c\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"video_slider\" data-widget_type=\"uael-video-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"uael-video-gallery-wrap uael-vg__layout-carousel uael-vg__action-inline uael-aspect-ratio-16_9\" data-action=\"inline\" data-layout=\"carousel\" data-all-filters=\"[&quot;filter-youtube&quot;]\" data-vg_slider=\"{&quot;slidesToShow&quot;:1,&quot;slidesToScroll&quot;:1,&quot;autoplaySpeed&quot;:5000,&quot;autoplay&quot;:false,&quot;infinite&quot;:true,&quot;pauseOnHover&quot;:false,&quot;speed&quot;:500,&quot;arrows&quot;:true,&quot;dots&quot;:false,&quot;rtl&quot;:false,&quot;prevArrow&quot;:&quot;&lt;button type=\\&quot;button\\&quot; data-role=\\&quot;none\\&quot; class=\\&quot;slick-prev\\&quot; aria-label=\\&quot;Previous\\&quot; tabindex=\\&quot;0\\&quot; role=\\&quot;button\\&quot;&gt;&lt;i class=\\&quot;fa fa-angle-left\\&quot;&gt;&lt;\\\/i&gt;&lt;\\\/button&gt;&quot;,&quot;nextArrow&quot;:&quot;&lt;button type=\\&quot;button\\&quot; data-role=\\&quot;none\\&quot; class=\\&quot;slick-next\\&quot; aria-label=\\&quot;Next\\&quot; tabindex=\\&quot;0\\&quot; role=\\&quot;button\\&quot;&gt;&lt;i class=\\&quot;fa fa-angle-right\\&quot;&gt;&lt;\\\/i&gt;&lt;\\\/button&gt;&quot;,&quot;responsive&quot;:[{&quot;breakpoint&quot;:1024,&quot;settings&quot;:{&quot;slidesToShow&quot;:1,&quot;slidesToScroll&quot;:1}},{&quot;breakpoint&quot;:767,&quot;settings&quot;:{&quot;slidesToShow&quot;:1,&quot;slidesToScroll&quot;:1}}]}\">\t\t\t\t<div class=\"uael-video__gallery-item\" id=\"uael-video__gallery-item1\">\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"uael-video__gallery-iframe\" style=\"background-image:url('https:\/\/i.ytimg.com\/vi\/vJugp2b0m4A\/maxresdefault.jpg');\">\n\t\t\t\t\t\t<a class=\"elementor-clickable uael-vg__play_full\" href=\"https:\/\/www.youtube.com\/watch?v=vJugp2b0m4A\" data-url=\"https:\/\/www.youtube.com\/embed\/vJugp2b0m4A?autoplay=1&amp;version=3&amp;enablejsapi=1\">\n\t\t\t\t\t\t\t<div class=\"uael-video__content-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"uael-video__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-vg__play\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-animation- uael-vg__play-icon\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"uael-vg__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-video__gallery-item\" id=\"uael-video__gallery-item2\">\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"uael-video__gallery-iframe\" style=\"background-image:url('https:\/\/i.ytimg.com\/vi\/vJugp2b0m4A\/maxresdefault.jpg');\">\n\t\t\t\t\t\t<a class=\"elementor-clickable uael-vg__play_full\" href=\"https:\/\/www.youtube.com\/watch?v=vJugp2b0m4A\" data-url=\"https:\/\/www.youtube.com\/embed\/vJugp2b0m4A?autoplay=1&amp;version=3&amp;enablejsapi=1\">\n\t\t\t\t\t\t\t<div class=\"uael-video__content-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"uael-video__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-vg__play\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-animation- uael-vg__play-icon\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"uael-vg__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-video__gallery-item\" id=\"uael-video__gallery-item3\">\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"uael-video__gallery-iframe\" style=\"background-image:url('https:\/\/i.ytimg.com\/vi\/vJugp2b0m4A\/maxresdefault.jpg');\">\n\t\t\t\t\t\t<a class=\"elementor-clickable uael-vg__play_full\" href=\"https:\/\/www.youtube.com\/watch?v=vJugp2b0m4A\" data-url=\"https:\/\/www.youtube.com\/embed\/vJugp2b0m4A?autoplay=1&amp;version=3&amp;enablejsapi=1\">\n\t\t\t\t\t\t\t<div class=\"uael-video__content-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"uael-video__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-vg__play\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-animation- uael-vg__play-icon\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"uael-vg__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\t\t<script type=\"text\/javascript\">\n\t\t\tjQuery( document ).ready( function( $ ) {\n\n\t\t\t\t$( '.uael-video-gallery-wrap' ).each( function() {\n\n\t\t\t\t\tvar $node_id \t= '3763ee6c';\n\t\t\t\t\tvar\tscope \t\t= $( '[data-id=\"' + $node_id + '\"]' );\n\t\t\t\t\tvar selector \t= $(this);\n\n\t\t\t\t\tif ( selector.closest( scope ).length < 1 ) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t}\n\n\t\t\t\t\tif ( ! selector.hasClass( 'uael-video-gallery-filter' ) ) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t}\n\n\t\t\t\t\tvar filters = scope.find( '.uael-video__gallery-filters' );\n\t\t\t\t\tvar def_cat = '*';\n\n\t\t\t\t\tif ( filters.length > 0 ) {\n\n\t\t\t\t\t\tvar def_filter = filters.data( 'default' );\n\n\t\t\t\t\t\tif ( '' !== def_filter ) {\n\n\t\t\t\t\t\t\tdef_cat \t= def_filter;\n\t\t\t\t\t\t\tdef_cat_sel = filters.find( '[data-filter=\"' + def_filter + '\"]' );\n\n\t\t\t\t\t\t\tif ( def_cat_sel.length > 0 ) {\n\t\t\t\t\t\t\t\tdef_cat_sel.siblings().removeClass( 'uael-filter__current' );\n\t\t\t\t\t\t\t\tdef_cat_sel.addClass( 'uael-filter__current' );\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t}\n\t\t\t\t\t}\n\n\t\t\t\t\tvar $obj = {};\n\n\t\t\t\t\tselector.imagesLoaded( function( e ) {\n\n\t\t\t\t\t\t$obj = selector.isotope({\n\t\t\t\t\t\t\tfilter: def_cat,\n\t\t\t\t\t\t\tlayoutMode: 'masonry',\n\t\t\t\t\t\t\titemSelector: '.uael-video__gallery-item',\n\t\t\t\t\t\t});\n\n\t\t\t\t\t\tselector.find( '.uael-video__gallery-item' ).resize( function() {\n\t\t\t\t\t\t\t$obj.isotope( 'layout' );\n\t\t\t\t\t\t});\n\t\t\t\t\t});\n\n\t\t\t\t});\n\t\t\t});\n\t\t<\/script>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-56f746a2\" data-id=\"56f746a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4268fae0 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"4268fae0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-386d4c5c\" data-id=\"386d4c5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-q_id=\"#about\" class=\"elementor-section elementor-top-section elementor-element elementor-element-28612ed elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"28612ed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-580a37f5\" data-id=\"580a37f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ec841c7 elementor-widget elementor-widget-image\" data-id=\"6ec841c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2020\/11\/heart.png\" title=\"c\u0153ur\" alt=\"c\u0153ur\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e5af88a elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"1e5af88a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-319cb728\" data-id=\"319cb728\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79f5c9fe elementor-widget elementor-widget-image\" data-id=\"79f5c9fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"63\" height=\"56\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/d.png\" class=\"attachment-full size-full wp-image-2275\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28728eaf free elementor-widget elementor-widget-text-editor\" data-id=\"28728eaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Confiserie Chocolette appartenant \u00e0 la Suisse<br \/>est n\u00e9 de la passion !<br \/>Le chocolat ROUGE est incroyablement d\u00e9licieux,<br \/>chocolat sans sucre ajout\u00e9.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7ca1ac55\" data-id=\"7ca1ac55\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-684416ac elementor-widget elementor-widget-image\" data-id=\"684416ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"53\" height=\"88\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/g.png\" class=\"attachment-full size-full wp-image-2282\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63154e8a free elementor-widget elementor-widget-text-editor\" data-id=\"63154e8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9tenteur de 10 brevets mondiaux,<br \/>notre usine est bas\u00e9e sur une nouvelle technologie<br \/>style innovant de production de certains des plus<br \/>voulaient des chocolats dans le monde.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-205c0567 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"205c0567\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-33ac5395\" data-id=\"33ac5395\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c90bf8c elementor-widget elementor-widget-image\" data-id=\"4c90bf8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"106\" height=\"73\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/f.png\" class=\"attachment-full size-full wp-image-2289\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c292b83 free elementor-widget elementor-widget-text-editor\" data-id=\"2c292b83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Construit selon les sp\u00e9cifications de pointe pour notre utilisation avec de l&#8217;eau<br \/>et purification de l&#8217;air, recyclage de l&#8217;eau, refroidissement gratuit<br \/>et technologies de r\u00e9cup\u00e9ration,<br \/>notre objectif est de rendre la terre heureuse avec nous<br \/>(nous savons que vous allez \u00eatre ravi de RED)&nbsp;!<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-375802f5\" data-id=\"375802f5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b6c1ee9 elementor-widget elementor-widget-image\" data-id=\"7b6c1ee9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"50\" height=\"72\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/l.png\" class=\"attachment-full size-full wp-image-2296\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f35235a free elementor-widget elementor-widget-text-editor\" data-id=\"1f35235a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;\u00e9quipement sur mesure a \u00e9t\u00e9 r\u00e9alis\u00e9 par les principaux<br \/>Fabricants allemands et suisses.<br \/>Cet \u00e9quipement unique brevet\u00e9 permet<br \/>nous pour produire du chocolat ROUGE avec moins de calories,<br \/>moins de mati\u00e8res grasses et sans sucre ajout\u00e9<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2df72906 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"2df72906\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41e7a58c elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"41e7a58c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-478bde9 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"478bde9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-449c8806\" data-id=\"449c8806\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4bf09550 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"4bf09550\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66a5c016\" data-id=\"66a5c016\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4dab3381 elementor-widget elementor-widget-heading\" data-id=\"4dab3381\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-xxl\">Ne nous croyez pas sur parole\u2026<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dcebcf3 elementor-widget elementor-widget-heading\" data-id=\"1dcebcf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">voici quelques raisons suppl\u00e9mentaires de nous faire confiance et de nous aimer !<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-524ca2b elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"524ca2b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2256d1a\" data-id=\"2256d1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d123624 elementor-widget elementor-widget-image\" data-id=\"d123624\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/01\/klbd.png\" title=\"klbd\" alt=\"klbd\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1b4c3b2a\" data-id=\"1b4c3b2a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3706655b elementor-widget elementor-widget-image\" data-id=\"3706655b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/01\/brgs.png\" title=\"brgs\" alt=\"brgs\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-21e3c6b3\" data-id=\"21e3c6b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2096a85 elementor-widget elementor-widget-image\" data-id=\"2096a85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/01\/gfree.png\" title=\"gfree\" alt=\"gfree\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11ac80dc elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"11ac80dc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-5b641048\" data-id=\"5b641048\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-41eadec7\" data-id=\"41eadec7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21a2a2ba elementor-widget elementor-widget-video\" data-id=\"21a2a2ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/RQfYbkRgbW4&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-6620e8c5\" data-id=\"6620e8c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a9f89a0 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"3a9f89a0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23b2f068\" data-id=\"23b2f068\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-q_id=\"#contact\" class=\"elementor-section elementor-top-section elementor-element elementor-element-43a8bbcc elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"43a8bbcc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-591fcefa\" data-id=\"591fcefa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3ebc2d7a elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"3ebc2d7a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6d97448e\" data-id=\"6d97448e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5da88a58 elementor-widget elementor-widget-text-editor\" data-id=\"5da88a58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Bureau<\/strong><br \/> Chocolette SA Rue Adrien-Lachel 26,<br \/>Gen\u00e8ve, CH 1207, Suisse<br \/>E : info@chocolette.com<\/p>\n<\/p>\n<p><strong>Bureau &amp; Chocolaterie Lettonie<\/strong><br \/>Confiserie Chocolette SIA<br \/>Aviacijas 18, Jelgava, LV-3004<br \/>T: +371 661 40 700<br \/>E : info@chocolette.com<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-3898d83f\" data-id=\"3898d83f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2739e912 elementor-widget elementor-widget-heading\" data-id=\"2739e912\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><strong>Votre message<\/strong><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-764e49b0 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"764e49b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;button_width&quot;:&quot;20&quot;,&quot;step_next_label&quot;:&quot;Prochain&quot;,&quot;step_previous_label&quot;:&quot;Pr\\u00e9c\\u00e9dent&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Contacter\" aria-label=\"Contacter\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"2735\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"764e49b0\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"RED Chocolette\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNom\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Nom\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-tel elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-tel\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tT\u00e9l\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[tel]\" id=\"form-field-tel\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"T&nbsp;:\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Seuls les caract\u00e8res de num\u00e9ros de t\u00e9l\u00e9phone (#, -, *, etc.) sont accept\u00e9s.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tE-mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Entrez votre adresse email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-text elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-text\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tUn message\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-xs\" name=\"form_fields[text]\" id=\"form-field-text\" rows=\"4\" placeholder=\"Texte\" required=\"required\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text\">\n\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_aa75486]\" id=\"form-field-field_aa75486\" class=\"elementor-field elementor-size-xs \" style=\"display:none !important;\">\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-20 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-xs\" type=\"submit\" id=\"form_button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">d'accord&gt;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-642b2138 elementor-section-height-min-height elementor-section-full_width elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"642b2138\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-485ce8d9\" data-id=\"485ce8d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>LA PREMI\u00c8REDANSLE MONDE Les barres de chocolat ROUGE ont \u00e9t\u00e9 judicieusement con\u00e7u pour sublimer vos papilles afin que vous puissiez profiter pleinement de la saveur de chaque bouch\u00e9e. D\u00c9LICIEUX&amp;L\u00c9GER Cr\u00e9\u00e9 par des Ma\u00eetres Chocolatiers de France et la Suisse, notre style unique et brevet\u00e9 cr\u00e9e&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"footnotes":""},"class_list":["post-2735","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>principale - RED Chocolette<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chocolette.com\/fr\/principale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"principale - RED Chocolette\" \/>\n<meta property=\"og:description\" content=\"LA PREMI\u00c8REDANSLE MONDE Les barres de chocolat ROUGE ont \u00e9t\u00e9 judicieusement con\u00e7u pour sublimer vos papilles afin que vous puissiez profiter pleinement de la saveur de chaque bouch\u00e9e. D\u00c9LICIEUX&amp;L\u00c9GER Cr\u00e9\u00e9 par des Ma\u00eetres Chocolatiers de France et la Suisse, notre style unique et brevet\u00e9 cr\u00e9e...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chocolette.com\/fr\/principale\/\" \/>\n<meta property=\"og:site_name\" content=\"RED Chocolette\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T13:34:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/almond.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"principale - RED Chocolette","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chocolette.com\/fr\/principale\/","og_locale":"fr_FR","og_type":"article","og_title":"principale - RED Chocolette","og_description":"LA PREMI\u00c8REDANSLE MONDE Les barres de chocolat ROUGE ont \u00e9t\u00e9 judicieusement con\u00e7u pour sublimer vos papilles afin que vous puissiez profiter pleinement de la saveur de chaque bouch\u00e9e. D\u00c9LICIEUX&amp;L\u00c9GER Cr\u00e9\u00e9 par des Ma\u00eetres Chocolatiers de France et la Suisse, notre style unique et brevet\u00e9 cr\u00e9e...","og_url":"https:\/\/chocolette.com\/fr\/principale\/","og_site_name":"RED Chocolette","article_modified_time":"2026-04-10T13:34:55+00:00","og_image":[{"url":"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/almond.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/chocolette.com\/fr\/principale\/","url":"https:\/\/chocolette.com\/fr\/principale\/","name":"principale - RED Chocolette","isPartOf":{"@id":"https:\/\/chocolette.com\/fr\/#website"},"datePublished":"2021-11-01T12:30:00+00:00","dateModified":"2026-04-10T13:34:55+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chocolette.com\/fr\/principale\/"]}]},{"@type":"WebSite","@id":"https:\/\/chocolette.com\/fr\/#website","url":"https:\/\/chocolette.com\/fr\/","name":"RED Chocolette","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chocolette.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/chocolette.com\/fr\/wp-json\/wp\/v2\/pages\/2735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chocolette.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/chocolette.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/chocolette.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chocolette.com\/fr\/wp-json\/wp\/v2\/comments?post=2735"}],"version-history":[{"count":1,"href":"https:\/\/chocolette.com\/fr\/wp-json\/wp\/v2\/pages\/2735\/revisions"}],"predecessor-version":[{"id":2740,"href":"https:\/\/chocolette.com\/fr\/wp-json\/wp\/v2\/pages\/2735\/revisions\/2740"}],"wp:attachment":[{"href":"https:\/\/chocolette.com\/fr\/wp-json\/wp\/v2\/media?parent=2735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}