{"id":2743,"date":"2021-11-01T15:30:02","date_gmt":"2021-11-01T12:30:02","guid":{"rendered":"https:\/\/chocolette.com\/hauptsaechlich\/"},"modified":"2026-04-10T16:34:55","modified_gmt":"2026-04-10T13:34:55","slug":"hauptsaechlich","status":"publish","type":"page","link":"https:\/\/chocolette.com\/de\/hauptsaechlich\/","title":{"rendered":"haupts\u00e4chlich"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2743\" class=\"elementor elementor-2743\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-q_id=\"#whyred\" class=\"elementor-section elementor-top-section elementor-element elementor-element-7ed2bf3c elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"7ed2bf3c\" data-element_type=\"section\" data-e-type=\"section\" id=\"section1\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-59f75ac1\" data-id=\"59f75ac1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-367072dc elementor-widget elementor-widget-heading\" data-id=\"367072dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DER ERSTE<div class=\"thin\">IN<\/div>DIE WELT<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd94097 elementor-widget elementor-widget-text-editor\" data-id=\"fd94097\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ROTE Schokoriegel wurden nachdenklich gemacht<\/p>\n<p>entwickelt, um Ihre Geschmacksknospen zu verbessern, damit Sie es k\u00f6nnen<\/p>\n<p><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif;\">Genie\u00dfen Sie den Geschmack bei jedem Bissen.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b9978ef\" data-id=\"b9978ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ef0b223 elementor-widget__width-inherit elementor--h-position-center elementor--v-position-middle elementor-widget elementor-widget-slides\" data-id=\"1ef0b223\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;none&quot;,&quot;transition&quot;:&quot;fade&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slider\" dir=\"ltr\" data-animation=\"fadeInRight\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-db3c901 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"1Folie\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-a2813d6 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"2Folie\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-77d05f0 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"3Folie\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-462b86c elementor-section-content-middle elementor-reverse-mobile elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"462b86c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4864656b\" data-id=\"4864656b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7061092b elementor-invisible elementor-widget elementor-widget-image\" data-id=\"7061092b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1070\" height=\"709\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/almond.jpg\" class=\"attachment-full size-full wp-image-2227\" alt=\"\" srcset=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/almond.jpg 1070w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/almond-300x199.jpg 300w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/almond-1024x679.jpg 1024w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/almond-768x509.jpg 768w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/almond-700x464.jpg 700w\" sizes=\"(max-width: 1070px) 100vw, 1070px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6fb33ef9\" data-id=\"6fb33ef9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b53e237 elementor-widget elementor-widget-image\" data-id=\"1b53e237\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2020\/11\/heart.png\" title=\"Herz\" alt=\"Herz\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46739ae0 elementor-widget elementor-widget-heading\" data-id=\"46739ae0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LECKER<div>&amp;<\/div><div>HELL<\/div><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d05f875 elementor-widget elementor-widget-text-editor\" data-id=\"d05f875\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kreiert von Meister-Chocolatiers aus Frankreich<\/p>\n<p>und der Schweiz schafft unser einzigartiger, patentierter Stil<\/p>\n<p>eine wohlschmeckende Schokolade ohne Zuckerzusatz und <\/p>\n<p>bis zu halb so viel Fett wie andere Schokoladen. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14ac1068 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"14ac1068\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f59f267\" data-id=\"3f59f267\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e418345 elementor-section-content-top elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"2e418345\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6288f953\" data-id=\"6288f953\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b920c95 elementor-widget elementor-widget-image\" data-id=\"7b920c95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2020\/11\/heart.png\" title=\"Herz\" alt=\"Herz\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23417b5d elementor-widget elementor-widget-heading\" data-id=\"23417b5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ALLES VERGN\u00dcGEN<div class=\"thin\">KEINER<\/div>DER SCHULD<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ee56505 elementor-widget elementor-widget-text-editor\" data-id=\"6ee56505\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>RED Dark Chocolette ist die erste Schokolade im<\/p>\n<p><span style=\"font-family: Circe, sans-serif;\">Welt&nbsp;<\/span><span style=\"font-family: Circe, sans-serif;\">enth\u00e4lt bis zu halb so viele Kalorien wie andere Dark&nbsp;<\/span><\/p>\n<p><span style=\"font-family: Circe, sans-serif;\">Pralinen.<\/span>&nbsp; <span style=\"font-family: Circe, sans-serif;\">RED wurde ohne Zusatz erstellt<\/span><\/p>\n<p>verarbeiteter Zucker, der uns unseren erstaunlichen Geschmack verleiht<\/p>\n<p>&nbsp;mit reduziertem Fettanteil. &nbsp;<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1ee1c74\" data-id=\"1ee1c74\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f77af44 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"6f77af44\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1070\" height=\"709\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/extra.jpg\" class=\"attachment-full size-full wp-image-1926\" alt=\"\" srcset=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/extra.jpg 1070w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/extra-300x199.jpg 300w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/extra-1024x679.jpg 1024w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/extra-768x509.jpg 768w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/extra-700x464.jpg 700w\" sizes=\"(max-width: 1070px) 100vw, 1070px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-q_id=\"#ingredients\" class=\"elementor-section elementor-top-section elementor-element elementor-element-74c8e71d elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"74c8e71d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2fcd40e8\" data-id=\"2fcd40e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-646d73ee elementor-widget elementor-widget-heading\" data-id=\"646d73ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ZUTATEN<div class=\"thin\">IN UNSERER<\/div>SCHOKOLADE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4dbde936\" data-id=\"4dbde936\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12926f11 elementor-widget elementor-widget-text-editor\" data-id=\"12926f11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unser Rezept basiert auf nat\u00fcrlichen Kakaoprodukten <\/p>\n<p>geliefert von der Elfenbeink\u00fcste (C\u00f4te d&#8217;Ivoire), <\/p>\n<p>Erythrit und Maltit sind sichere nat\u00fcrliche S\u00fc\u00dfstoffe, <\/p>\n<p>Polydextrose reich an Nahrungsfasern.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c734052 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"5c734052\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-25cf47b2\" data-id=\"25cf47b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f49d297 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"2f49d297\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1070\" height=\"709\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/coffee.jpg\" class=\"attachment-full size-full wp-image-1954\" alt=\"\" srcset=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/coffee.jpg 1070w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/coffee-300x199.jpg 300w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/coffee-1024x679.jpg 1024w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/coffee-768x509.jpg 768w, https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/coffee-700x464.jpg 700w\" sizes=\"(max-width: 1070px) 100vw, 1070px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fd8dd50 elementor-widget elementor-widget-spacer\" data-id=\"1fd8dd50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-30c726ea\" data-id=\"30c726ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42fb9f08 elementor-widget elementor-widget-heading\" data-id=\"42fb9f08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"thin\">WAS IST UNSERE SCHOKOLADE<br>HERGESTELLT AUS?<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f50d068 elementor-widget elementor-widget-text-editor\" data-id=\"2f50d068\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hochwertige Kakaoprodukte sind das Herzst\u00fcck von Red Chocolate. Wir verwenden Kakaoprodukte der besten Lieferanten der Elfenbeink\u00fcste. Unsere Mission ist es, wohlschmeckende Schokolade zu produzieren, die auch gesund ist, und wir gehen dabei keine Kompromisse ein!<br \/>\n<br \/>\nUnsere Lieferanten besitzen eigene Kakaofarmen und halten h\u00f6chste Standards bei der Auswahl, R\u00f6stung und Vermahlung der Kakaobohnen ein. Das Ziel ist es, die feinsten Geschmacks- und Aromanoten freizusetzen und gleichzeitig sicherzustellen, dass der Endgeschmack reich und voll ist.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d927031 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"1d927031\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-21f326a5\" data-id=\"21f326a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-146c0bec elementor-widget elementor-widget-heading\" data-id=\"146c0bec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NAT\u00dcRLICHE QUELLEN<br><div class=\"thin\">DER S\u00dcSSIGKEIT<span style=\"font-family: Circe, sans-serif\"><\/span><\/div><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-145aa8d3\" data-id=\"145aa8d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17b75cf6 elementor-widget elementor-widget-image\" data-id=\"17b75cf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" title=\"cocoa\" alt=\"cocoa\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f0af832 elementor-widget elementor-widget-image\" data-id=\"5f0af832\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/100quality.png\" title=\"100Qualit\u00e4t\" alt=\"100Qualit\u00e4t\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dc444d4 rose elementor-widget elementor-widget-text-editor\" data-id=\"4dc444d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die feinste Elfenbeink\u00fcste<\/p>\n<p>&nbsp;Kakaobohnen geben unserer Schokolade ihre<\/p>\n<p>&nbsp;charakteristischer Geschmack<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78d39b0d elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"78d39b0d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5f113541\" data-id=\"5f113541\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20aa7c30 elementor-widget elementor-widget-image\" data-id=\"20aa7c30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/melon.png\" title=\"Melone\" alt=\"Melone\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50948d14 rose elementor-widget elementor-widget-text-editor\" data-id=\"50948d14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Polydextrose &#8211; eine reichhaltige Quelle<\/p>\n<p>aus Nahrungsfasern aus nat\u00fcrlichen<\/p>\n<p>Zutaten helfen, unsere Schokolade zu halten<\/p>\n<p>gesundheitsbewusst.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-51442f15\" data-id=\"51442f15\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6100a6fe elementor-widget elementor-widget-image\" data-id=\"6100a6fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/praline1.png\" title=\"Praline1\" alt=\"Praline1\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1c9035c8\" data-id=\"1c9035c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54e99521 elementor-widget elementor-widget-image\" data-id=\"54e99521\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" title=\"leaf\" alt=\"leaf\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a70a930 rose elementor-widget elementor-widget-text-editor\" data-id=\"5a70a930\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ein kalorienfreies pflanzliches<br \/>S\u00fc\u00dfstoff Erythrit, auch bekannt<br \/>wie \u201eMelonenzucker\u201c verbessert<br \/>die S\u00fc\u00dfe unserer Schokolade<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d628095 elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"7d628095\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-40c2fc17\" data-id=\"40c2fc17\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3358235 elementor-widget elementor-widget-image\" data-id=\"3358235\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cook.png\" title=\"Kochen\" alt=\"Kochen\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54069b65 rose elementor-widget elementor-widget-text-editor\" data-id=\"54069b65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die einzigartige Verarbeitung<br \/>von Rohstoffen erm\u00f6glicht es uns, den perfekten Geschmack zu kreieren.<br \/>Wir machen unsere Schokolade bei einer Temperatur von 55\u00baC<br \/>(anstelle von regul\u00e4ren 80 \u00b0 C).<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7847bc16\" data-id=\"7847bc16\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-725c3f8e elementor-widget elementor-widget-image\" data-id=\"725c3f8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/diamond.png\" title=\"Diamant\" alt=\"Diamant\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f3fdb0 rose elementor-widget elementor-widget-text-editor\" data-id=\"3f3fdb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die einzigartige Rautenform<br \/>von Schokolade und Pralinen<br \/>Erlaube den Rezeptoren, das Perfekte zu sp\u00fcren<br \/>ge\u00f6ffneter Geschmack von Schokolade<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-q_id=\"#discover\" class=\"elementor-section elementor-top-section elementor-element elementor-element-55e8f40a elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"55e8f40a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7153bb2b\" data-id=\"7153bb2b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f790e25 elementor-widget elementor-widget-slider_revolution\" data-id=\"3f790e25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"slider_revolution.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"wp-block-themepunch-revslider\">\n\t\t\t<!-- START Products REVOLUTION SLIDER 6.7.40 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_1_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_1_1\" style=\"\" data-version=\"6.7.40\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-91\" data-title=\"Extra\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2020\/12\/UK_EXD_CMYK_01.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\" class=\"extra\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Extra\" title=\"coffee\" width=\"1013\" height=\"782\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-bg=\"p:60% 50%;f:auto;\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-91-layer-0\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,46px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-91-layer-3\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:775px,640px,486px,10px;yo:225px,185px,140px,240px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-91-layer-4\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-bsh=\"c:#000000;v:10px,8px,6px,3px;b:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,15px;yo:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:230px,189px,143px,40%;h:500px,412px,313px,auto;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:extra_old;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1080\" height=\"2347\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/04\/PENAL_EU_EXTRA_DARK_100g_FRONT-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-91-layer-5\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:69px,56px,42px,27px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,22;l:90,74,56,34;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>EXTRA \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-91-layer-11\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:141px,116px,88px,61px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:24,19,14,14;l:24,19,14,16;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;h:auto,auto,auto,36px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;font-family:'Circe';\"\n\t\t\t\t\t\t\t>DUNKLE SCHOKOLADE \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-91-layer-12\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:172px,142px,107px,102px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>383 kcal \/ 100 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-91-layer-13\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer fancybox-iframe\"\n\t\t\t\t\t\t\t\thref=\"#ninja-popup-4290\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:811px,669px,508px,27px;yo:495px,408px,309px,400px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:30,24,18,21;l:27,22,16,17;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:129px,106px,80px,63px;h:41px,33px,25px,28px;\"\n\t\t\t\t\t\t\t\tdata-margin=\"t:15,12,9,6;r:10,8,6,4;b:15,12,9,6;l:10,8,6,4;\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:8,7,5,6;r:5,4,3,4;b:5,4,3,4;l:5,4,3,4;\"\n\t\t\t\t\t\t\t\tdata-border=\"bos:solid;boc:#5d0900;bow:1px,1px,1px,1px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bgc:#d4b06d;boc:#dc0028;bos:solid;bow:0px,0px,0px,0px;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:11;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>KAUFEN \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-91-layer-14\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:319px,263px,199px,50px;yo:390px,322px,244px,290px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:110px,90px,68px,87px;h:110px,90px,68px,87px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:590;sp:600;sR:590;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7810;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:17;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"396\" height=\"396\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/12\/60-\u043a\u0430\u043a\u0430\u043e@2x.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-91-layer-63\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:255px,210px,159px,17px;yo:11px,9px,6px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-91-layer-64\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:244px,201px,152px,335px;yo:224px,184px,139px,128px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:142px,117px,88px,88px;h:58px,47px,35px,53px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:18;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"215\" height=\"88\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2022\/09\/21_2.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-91-layer-112\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:788px,650px,493px,10px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:316px,260px,197px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:extra_old;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>WEITERE INFORMATIONEN \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-92\" data-title=\"Dark\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2020\/12\/UK_DS_CMYK_01.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Dark\" title=\"haupts\u00e4chlich\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-92-layer-22\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:788px,650px,493px,15px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:318px,262px,199px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:extra_old-1;ms:rs-24;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>WEITERE INFORMATIONEN \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-92-layer-23\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer fancybox-iframe\"\n\t\t\t\t\t\t\t\thref=\"#ninja-popup-4290\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:811px,669px,508px,27px;yo:495px,408px,309px,400px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:30,24,18,21;l:27,22,16,17;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:130px,107px,81px,63px;h:41px,33px,25px,28px;\"\n\t\t\t\t\t\t\t\tdata-margin=\"t:15,12,9,6;r:10,8,6,4;b:15,12,9,6;l:10,8,6,4;\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:8,7,5,6;r:5,4,3,4;b:5,4,3,4;l:5,4,3,4;\"\n\t\t\t\t\t\t\t\tdata-border=\"bos:solid;boc:#5d0900;bow:1px,1px,1px,1px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bgc:#d4b06d;boc:#dc0028;bos:solid;bow:0px,0px,0px,0px;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:11;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>KAUFEN \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-92-layer-58\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:69px,56px,42px,27px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,22;l:90,74,56,34;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>DUNKLE  \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-92-layer-81\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:255px,210px,159px,17px;yo:11px,9px,6px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-92-layer-86\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:244px,201px,152px,335px;yo:210px,173px,131px,128px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:142px,117px,88px,88px;h:58px,47px,35px,53px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"215\" height=\"88\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2022\/09\/21_2.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-92-layer-139\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:141px,116px,88px,61px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:24,19,14,14;l:24,19,14,16;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;h:auto,auto,auto,36px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;font-family:'Circe';\"\n\t\t\t\t\t\t\t>SCHOKOLADE \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-92-layer-141\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:172px,142px,107px,102px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>373 kcal \/ 100 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-92-layer-146\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,46px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-92-layer-147\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:775px,640px,486px,10px;yo:225px,185px,140px,240px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-92-layer-148\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-bsh=\"c:#000000;v:10px,8px,6px,3px;b:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,15px;yo:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:230px,189px,143px,40%;h:500px,412px,313px,auto;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:extra_old-1;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1080\" height=\"2347\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/04\/PENAL_EU_DARK_100g_FRONT-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-93\" data-title=\"Orange\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2020\/12\/UK_OA_CMYK_01.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Orange\" title=\"haupts\u00e4chlich\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-93-layer-71\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:395px,326px,247px,73px;yo:451px,372px,282px,380px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:90px,74px,56px,55px;h:97px,80px,60px,59px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:600;sp:600;sR:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7800;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:18;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"158\" height=\"170\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/almond-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-93-layer-72\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:285px,235px,178px,27px;yo:303px,250px,189px,258px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:166px,137px,104px,117px;h:202px,166px,126px,142px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:610;sp:600;sR:610;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7790;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:19;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"269\" height=\"327\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/orange.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-93-layer-88\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:255px,210px,159px,16px;yo:11px,9px,6px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-93-layer-89\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:244px,201px,152px,335px;yo:210px,173px,131px,191px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:142px,117px,88px,88px;h:58px,47px,35px,53px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:17;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"215\" height=\"88\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2022\/09\/21_2.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-93-layer-110\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:788px,650px,493px,15px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:316px,260px,197px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:dark-n-1;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>WEITERE INFORMATIONEN \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-93-layer-111\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer fancybox-iframe\"\n\t\t\t\t\t\t\t\thref=\"#ninja-popup-4290\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:811px,669px,508px,27px;yo:495px,408px,309px,400px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:30,24,18,21;l:27,22,16,17;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:129px,106px,80px,63px;h:41px,33px,25px,28px;\"\n\t\t\t\t\t\t\t\tdata-margin=\"t:15,12,9,6;r:10,8,6,4;b:15,12,9,6;l:10,8,6,4;\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:8,7,5,6;r:5,4,3,4;b:5,4,3,4;l:5,4,3,4;\"\n\t\t\t\t\t\t\t\tdata-border=\"bos:solid;boc:#5d0900;bow:1px,1px,1px,1px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bgc:#d4b06d;boc:#dc0028;bos:solid;bow:0px,0px,0px,0px;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:11;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>KAUFEN \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-93-layer-149\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:45px,37px,28px,27px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,22;l:45,37,28,30;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>ORANGE UND<br \/>\nMANDEL \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-93-layer-150\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:141px,116px,88px,123px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:24,19,14,14;l:24,19,14,16;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;h:auto,auto,auto,36px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;font-family:'Circe';\"\n\t\t\t\t\t\t\t>DUNKLE SCHOKOLADE \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-93-layer-151\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:172px,142px,107px,164px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>378 kcal \/ 100 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-93-layer-152\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,46px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-93-layer-153\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:775px,640px,486px,10px;yo:225px,185px,140px,240px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-93-layer-154\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-bsh=\"c:#000000;v:10px,8px,6px,3px;b:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,15px;yo:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:230px,189px,143px,40%;h:500px,412px,313px,auto;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:dark-n-1;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1080\" height=\"2347\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/04\/PENAL_EU_DARK_OA_100g_FRONT-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-94\" data-title=\"Milk\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2020\/12\/UK_MS_CMYK_01.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Milk\" title=\"haupts\u00e4chlich\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-94-layer-61\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-308px,-254px,-192px,335px;yo:68px,56px,42px,27px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:33,27,20,22;l:90,74,56,34;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>MILCHSCHOKOLADE \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-94-layer-70\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:255px,210px,159px,-10px;yo:244px,201px,152px,153px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:278px,229px,173px,206px;h:328px,270px,205px,243px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:590;sp:600;sR:590;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7810;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"483\" height=\"570\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/milk.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-94-layer-91\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:255px,210px,159px,17px;yo:11px,9px,6px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-94-layer-95\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:244px,201px,152px,335px;yo:210px,173px,131px,128px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:142px,117px,88px,88px;h:57px,47px,35px,53px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:17;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"218\" height=\"87\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2022\/09\/22_1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-94-layer-115\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:788px,650px,493px,15px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:315px,260px,197px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:dark-n-11;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>WEITERE INFORMATIONEN \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-94-layer-116\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer fancybox-iframe\"\n\t\t\t\t\t\t\t\thref=\"#ninja-popup-4290\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:811px,669px,508px,27px;yo:495px,408px,309px,400px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:30,24,18,21;l:27,22,16,17;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:130px,107px,81px,63px;h:41px,33px,25px,28px;\"\n\t\t\t\t\t\t\t\tdata-margin=\"t:15,12,9,6;r:10,8,6,4;b:15,12,9,6;l:10,8,6,4;\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:8,7,5,6;r:5,4,3,4;b:5,4,3,4;l:5,4,3,4;\"\n\t\t\t\t\t\t\t\tdata-border=\"bos:solid;boc:#5d0900;bow:1px,1px,1px,1px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bgc:#d4b06d;boc:#dc0028;bos:solid;bow:0px,0px,0px,0px;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>KAUFEN \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-94-layer-157\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:172px,142px,107px,102px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>393 kcal \/ 100 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-94-layer-158\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,46px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-94-layer-159\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:775px,640px,486px,10px;yo:225px,185px,140px,240px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-94-layer-160\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-bsh=\"c:#000000;v:10px,8px,6px,3px;b:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,15px;yo:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:230px,189px,143px,40%;h:500px,412px,313px,auto;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:dark-n-11;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1080\" height=\"2347\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/01\/PENAL_NEW_3D-UK-MILK-TEMPLATE-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-96\" data-title=\"Macadamia\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2020\/12\/UK_HM_CMYK_01.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Macadamia\" title=\"haupts\u00e4chlich\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-96-layer-67\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:318px,262px,199px,40px;yo:314px,259px,196px,261px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:154px,127px,96px,115px;h:176px,145px,110px,131px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:600;sp:600;sR:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7800;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:18;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"273\" height=\"312\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/hazelnut.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-96-layer-100\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:255px,210px,159px,17px;yo:11px,9px,6px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-96-layer-102\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:244px,201px,152px,335px;yo:210px,173px,131px,191px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:142px,117px,88px,88px;h:57px,47px,35px,53px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:17;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"218\" height=\"87\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2022\/09\/22_1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-96-layer-127\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:788px,650px,493px,15px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:314px,259px,196px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:apple-n-1;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>WEITERE INFORMATIONEN \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-96-layer-128\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer fancybox-iframe\"\n\t\t\t\t\t\t\t\thref=\"#ninja-popup-4290\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:811px,669px,508px,27px;yo:495px,408px,309px,400px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:30,24,18,21;l:27,22,16,17;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:130px,107px,81px,63px;h:41px,33px,25px,28px;\"\n\t\t\t\t\t\t\t\tdata-margin=\"t:15,12,9,6;r:10,8,6,4;b:15,12,9,6;l:10,8,6,4;\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:8,7,5,6;r:5,4,3,4;b:5,4,3,4;l:5,4,3,4;\"\n\t\t\t\t\t\t\t\tdata-border=\"bos:solid;boc:#5d0900;bow:1px,1px,1px,1px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bgc:#d4b06d;boc:#dc0028;bos:solid;bow:0px,0px,0px,0px;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:11;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>KAUFEN \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-96-layer-167\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:45px,37px,28px,27px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,22;l:45,37,28,30;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,138px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>HASELNUSS UND<br \/>\nMACADEMIA \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-96-layer-168\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:141px,116px,88px,123px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:24,19,14,14;l:24,19,14,16;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,161px;h:auto,auto,auto,36px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;font-family:'Circe';\"\n\t\t\t\t\t\t\t>MILCHSCHOKOLADE \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-96-layer-169\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:172px,142px,107px,164px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>403 kcal \/ 100 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-96-layer-170\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-bsh=\"c:#000000;v:10px,8px,6px,3px;b:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,15px;yo:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:230px,189px,143px,40%;h:500px,412px,313px,auto;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:apple-n-1;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1080\" height=\"2347\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/01\/PENAL_NEW_3D-UK-HM-TEMPLATE-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-96-layer-171\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,46px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-96-layer-172\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:775px,640px,486px,10px;yo:225px,185px,140px,240px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-520\" data-title=\"Caramel\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2022\/08\/\u041a\u0410\u0420\u0410\u041c\u0415\u041b\u042c\u041d\u042b\u0419.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Caramel\" title=\"haupts\u00e4chlich\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-520-layer-10\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-296px,-244px,-185px,334px;yo:44px,36px,27px,27px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:32,26,19,18;l:45,37,28,30;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,172px;minh:0,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>KARAMELLISIERTE <br \/>\nWEI\u00dfE SCHOKOLADE <br \/>\n \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-520-layer-15\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:380px,313px,237px,49px;yo:435px,359px,272px,313px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:130px,107px,81px,111px;h:98px,80px,60px,83px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:590;sp:600;sR:590;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7810;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:18;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"276\" height=\"207\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2022\/07\/\u0420\u0435\u0441\u0443\u0440\u0441-11@2x.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-520-layer-21\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,335px;yo:141px,116px,88px,94px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:24,19,14,14;l:24,19,14,16;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;h:auto,auto,auto,36px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;font-family:'Circe';\"\n\t\t\t\t\t\t\t>BLONDE \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-520-layer-70\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:255px,210px,159px,-10px;yo:244px,201px,152px,153px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:278px,229px,173px,206px;h:328px,270px,205px,243px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:590;sp:600;sR:590;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7810;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"483\" height=\"570\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/milk.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-520-layer-91\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:255px,210px,159px,17px;yo:11px,9px,6px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8700;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-520-layer-95\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:238px,196px,148px,335px;yo:210px,173px,131px,142px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:140px,115px,87px,88px;h:55px,45px,34px,32px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8700;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:17;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"221\" height=\"86\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/01\/\u0420\u0435\u0441\u0443\u0440\u0441-15.svg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-520-layer-115\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:788px,650px,493px,-5px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,14;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:202px,166px,126px,139px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:caramel-n;sp:1;bg:rgba(0,0,0,0.5);'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>WEITERE INFORMATIONEN \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-520-layer-116\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer fancybox-iframe\"\n\t\t\t\t\t\t\t\thref=\"#ninja-popup-4290\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:811px,669px,508px,16px;yo:495px,408px,309px,398px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:30,24,18,21;l:27,22,16,17;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:130px,107px,81px,92px;h:41px,33px,25px,28px;\"\n\t\t\t\t\t\t\t\tdata-margin=\"t:15,12,9,6;r:10,8,6,4;b:15,12,9,6;l:10,8,6,4;\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:8,7,5,6;r:5,4,3,4;b:5,4,3,4;l:5,4,3,4;\"\n\t\t\t\t\t\t\t\tdata-border=\"bos:solid;boc:#5d0900;bow:1px,1px,1px,1px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bgc:#d4b06d;boc:#dc0028;bos:solid;bow:0px,0px,0px,0px;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>KAUFEN \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-520-layer-157\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-306px,-252px,-191px,335px;yo:172px,142px,107px,122px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>481 kcal \/ 100 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-520-layer-158\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,46px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-520-layer-159\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:775px,640px,486px,10px;yo:225px,185px,140px,240px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-520-layer-160\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-bsh=\"c:#000000;v:10px,8px,6px,3px;b:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,15px;yo:50px,41px,31px,19px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:230px,189px,143px,40%;h:497px,410px,311px,auto;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:caramel-n;bg:rgba(0,0,0,0.5);'\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1080\" height=\"2333\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/01\/PENAL_NEW_3D-UK-BLONDE-TEMPLATE-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-98\" data-title=\"Pralines\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/milk-candy.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Pralines\" title=\"haupts\u00e4chlich\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-98-layer-18\" \n\t\t\t\t\t\t\t\tclass=\"box\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,35px;y:m;yo:-80px,-70px,-65px,-140px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:528px,425px,322px,322px;h:470px,378px,287px,287px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:nutfil-n-1;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"772\" height=\"687\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/pralines.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-98-layer-25\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:202px,166px,126px,17px;yo:45px,37px,28px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:799px,659px,500px,462px;h:667px,550px,417px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-98-layer-73\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:220px,181px,137px,350px;yo:302px,249px,189px,192px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:176px,145px,110px,85px;h:70px,57px,43px,34px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:600;sp:600;sR:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7800;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:19;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"304\" height=\"121\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/praline.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-98-layer-134\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:842px,695px,528px,15px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:280px,231px,175px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:nutfil-n-1;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>WEITERE INFORMATIONEN \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-98-layer-135\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer fancybox-iframe\"\n\t\t\t\t\t\t\t\thref=\"#ninja-popup-4290\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:865px,714px,542px,27px;yo:495px,408px,309px,400px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:30,24,18,21;l:27,22,16,17;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:130px,107px,81px,63px;h:41px,33px,25px,28px;\"\n\t\t\t\t\t\t\t\tdata-margin=\"t:15,12,9,6;r:10,8,6,4;b:15,12,9,6;l:10,8,6,4;\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:8,7,5,6;r:5,4,3,4;b:5,4,3,4;l:5,4,3,4;\"\n\t\t\t\t\t\t\t\tdata-border=\"bos:solid;boc:#5d0900;bow:1px,1px,1px,1px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bgc:#d4b06d;boc:#dc0028;bos:solid;bow:0px,0px,0px,0px;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:11;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>KAUFEN \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-98-layer-179\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,365px;yo:69px,56px,42px,26px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,22;l:90,74,56,30;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,110px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>NUSSF\u00dcLLUNG \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-98-layer-180\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,365px;yo:141px,116px,88px,92px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:24,19,14,14;l:24,19,14,16;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;h:auto,auto,auto,36px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;font-family:'Circe';\"\n\t\t\t\t\t\t\t>MILCHPRALINEN \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-98-layer-181\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,365px;yo:172px,142px,107px,133px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>428 kcal \/ 100 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-98-layer-183\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-98-layer-184\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:571px,471px,357px,227px;yo:25px,20px,15px,320px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-98-layer-185\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:365px,301px,228px,38px;yo:491px,405px,307px,276px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:139px,114px,86px,91px;h:113px,93px,70px,74px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:nutfil-n-1;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:590;sp:600;sR:590;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7810;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:18;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"218\" height=\"177\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/macadamia.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-99\" data-title=\"Coconut\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/coconut.jpg\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Coconut\" title=\"haupts\u00e4chlich\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-99-layer-9\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:571px,471px,357px,227px;yo:25px,20px,15px,320px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-99-layer-30\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:842px,695px,528px,15px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:294px,242px,183px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:pralines-nut-n-1;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>WEITERE INFORMATIONEN \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-99-layer-31\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer fancybox-iframe\"\n\t\t\t\t\t\t\t\thref=\"#ninja-popup-4290\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:865px,714px,542px,27px;yo:495px,408px,309px,400px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:30,24,18,21;l:27,22,16,17;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:130px,107px,81px,63px;h:41px,33px,25px,28px;\"\n\t\t\t\t\t\t\t\tdata-margin=\"t:15,12,9,6;r:10,8,6,4;b:15,12,9,6;l:10,8,6,4;\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:8,7,5,6;r:5,4,3,4;b:5,4,3,4;l:5,4,3,4;\"\n\t\t\t\t\t\t\t\tdata-border=\"bos:solid;boc:#5d0900;bow:1px,1px,1px,1px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bgc:#d4b06d;boc:#dc0028;bos:solid;bow:0px,0px,0px,0px;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>KAUFEN \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-99-layer-42\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:202px,166px,126px,17px;yo:45px,37px,28px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:799px,659px,500px,462px;h:667px,550px,417px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-99-layer-85\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:304px,251px,190px,43px;yo:440px,363px,275px,259px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:220px,181px,137px,125px;h:217px,179px,135px,123px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:600;sp:600;sR:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7800;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"405\" height=\"400\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/coco1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-99-layer-186\" \n\t\t\t\t\t\t\t\tclass=\"box\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,35px;y:m;yo:-80px,-70px,-65px,-140px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:528px,425px,322px,322px;h:470px,378px,287px,286px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:pralines-nut-n-1;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"776\" height=\"690\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/coconut.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-99-layer-188\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-99-layer-189\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:220px,181px,137px,350px;yo:302px,249px,189px,192px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:176px,145px,110px,85px;h:70px,57px,43px,34px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:600;sp:600;sR:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7800;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:19;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"304\" height=\"121\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/praline.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-99-layer-191\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,365px;yo:172px,142px,107px,133px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:233px,192px,145px,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>405 kcal \/ 100 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-99-layer-192\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,365px;yo:141px,116px,88px,92px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:24,19,14,14;l:24,19,14,16;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;h:auto,auto,auto,36px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;font-family:'Circe';\"\n\t\t\t\t\t\t\t>MILCHPRALINEN \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-99-layer-193\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,365px;yo:81px,66px,50px,26px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,22;l:45,37,28,30;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,110px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>KOKOSF\u00dcLLUNG \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-100\" data-title=\"Dark Bar\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/02\/dark-bar.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Dark Bar\" title=\"haupts\u00e4chlich\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-100-layer-38\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:842px,695px,528px,15px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:308px,254px,192px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:dark-n-12;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>WEITERE INFORMATIONEN \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-100-layer-40\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer fancybox-iframe\"\n\t\t\t\t\t\t\t\thref=\"#ninja-popup-4290\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:865px,714px,542px,27px;yo:495px,408px,309px,400px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:30,24,18,21;l:27,22,16,17;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:131px,108px,82px,63px;h:41px,33px,25px,28px;\"\n\t\t\t\t\t\t\t\tdata-margin=\"t:15,12,9,6;r:10,8,6,4;b:15,12,9,6;l:10,8,6,4;\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:8,7,5,6;r:5,4,3,4;b:5,4,3,4;l:5,4,3,4;\"\n\t\t\t\t\t\t\t\tdata-border=\"bos:solid;boc:#5d0900;bow:1px,1px,1px,1px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bgc:#d4b06d;boc:#dc0028;bos:solid;bow:0px,0px,0px,0px;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:11;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>KAUFEN \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-100-layer-51\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:230px,189px,143px,17px;yo:74px,61px,46px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-100-layer-136\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,8px;y:m;yo:-85px,-70px,-55px,-110px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:500px,412px,313px,313px;h:284px,234px,177px,178px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:dark-n-12;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"600\" height=\"341\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/01\/Chocolate-Bars_NEW-3d-UK_DARK-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-100-layer-196\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-100-layer-199\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:172px,142px,107px,133px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>100 kcal \/ 26 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-100-layer-200\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:141px,116px,88px,92px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:24,19,14,14;l:24,19,14,16;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;h:auto,auto,auto,36px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;font-family:'Circe';\"\n\t\t\t\t\t\t\t>DUNKLE SCHOKOLADE \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-100-layer-209\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:498px,411px,312px,180px;yo:69px,56px,42px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-101\" data-title=\"Orange Bar\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/02\/dark-orange-bar.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Orange Bar\" title=\"haupts\u00e4chlich\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-101-layer-6\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:498px,411px,312px,180px;yo:69px,56px,42px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-101-layer-54\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:842px,695px,528px,15px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:315px,260px,197px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:oa-n-11;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>WEITERE INFORMATIONEN \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-101-layer-55\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer fancybox-iframe\"\n\t\t\t\t\t\t\t\thref=\"#ninja-popup-4290\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:865px,714px,542px,27px;yo:495px,408px,309px,400px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:30,24,18,21;l:27,22,16,17;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:128px,105px,79px,63px;h:41px,33px,25px,28px;\"\n\t\t\t\t\t\t\t\tdata-margin=\"t:15,12,9,6;r:10,8,6,4;b:15,12,9,6;l:10,8,6,4;\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:8,7,5,6;r:5,4,3,4;b:5,4,3,4;l:5,4,3,4;\"\n\t\t\t\t\t\t\t\tdata-border=\"bos:solid;boc:#5d0900;bow:1px,1px,1px,1px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bgc:#d4b06d;boc:#dc0028;bos:solid;bow:0px,0px,0px,0px;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:11;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>KAUFEN \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-101-layer-107\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:567px,468px,355px,192px;yo:455px,375px,284px,305px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:90px,74px,56px,53px;h:97px,80px,60px,57px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:600;sp:600;sR:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7800;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:17;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"158\" height=\"170\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/almond-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-101-layer-108\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:671px,554px,420px,250px;yo:397px,327px,248px,283px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:166px,137px,104px,107px;h:202px,166px,126px,130px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:610;sp:600;sR:610;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7790;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:18;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"269\" height=\"327\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/orange.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-101-layer-138\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:230px,189px,143px,17px;yo:74px,61px,46px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-101-layer-202\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:141px,116px,88px,118px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:24,19,14,14;l:24,19,14,16;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;h:auto,auto,auto,36px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;font-family:'Circe';\"\n\t\t\t\t\t\t\t>DUNKLE SCHOKOLADE \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-101-layer-203\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:172px,142px,107px,159px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>100 kcal \/ 26 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-101-layer-205\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-101-layer-207\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,8px;y:m;yo:-85px,-70px,-55px,-110px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:500px,412px,313px,313px;h:284px,234px,177px,178px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:oa-n-11;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"600\" height=\"341\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/01\/Chocolate-Bars_NEW-3d-UK_DARK_OA-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-101-layer-208\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:45px,37px,28px,26px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,22;l:45,37,28,30;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,110px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>ORANGE UND<br \/>\nMANDEL \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-102\" data-title=\"Milk Bar\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/milkbar1.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Milk Bar\" title=\"haupts\u00e4chlich\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-102-layer-7\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:498px,411px,312px,180px;yo:69px,56px,42px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-102-layer-46\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:842px,695px,528px,15px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:308px,254px,192px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:milk-n-1;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-padding=\"t:0,0,0,5;b:0,0,0,5;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>WEITERE INFORMATIONEN \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-102-layer-47\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer fancybox-iframe\"\n\t\t\t\t\t\t\t\thref=\"#ninja-popup-4290\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:865px,714px,542px,27px;yo:495px,408px,309px,400px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:30,24,18,21;l:27,22,16,17;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:131px,108px,82px,63px;h:41px,33px,25px,28px;\"\n\t\t\t\t\t\t\t\tdata-margin=\"t:15,12,9,6;r:10,8,6,4;b:15,12,9,6;l:10,8,6,4;\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:8,7,5,6;r:5,4,3,4;b:5,4,3,4;l:5,4,3,4;\"\n\t\t\t\t\t\t\t\tdata-border=\"bos:solid;boc:#5d0900;bow:1px,1px,1px,1px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bgc:#d4b06d;boc:#dc0028;bos:solid;bow:0px,0px,0px,0px;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:11;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>KAUFEN \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-102-layer-140\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:230px,189px,143px,17px;yo:74px,61px,46px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-102-layer-210\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:141px,116px,88px,92px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:24,19,14,14;l:24,19,14,16;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;h:auto,auto,auto,36px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;font-family:'Circe';\"\n\t\t\t\t\t\t\t>MILCHSCHOKOLADE \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-102-layer-211\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:172px,142px,107px,133px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>100 kcal \/ 26 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-102-layer-213\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-102-layer-215\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,8px;y:m;yo:-85px,-70px,-55px,-110px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:500px,412px,313px,313px;h:284px,234px,177px,178px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:milk-n-1;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"600\" height=\"341\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/01\/Chocolate-Bars_NEW-3d-UK_MILK-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-103\" data-title=\"Milk HM\" data-thumb=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/02\/milk-bar.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Milk HM\" title=\"haupts\u00e4chlich\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-103-layer-8\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:498px,411px,312px,180px;yo:69px,56px,42px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,133px,101px,106px;h:173px,142px,107px,114px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:580;sp:600;sR:580;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7820;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"254\" height=\"272\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/leaf.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-103-layer-122\" \n\t\t\t\t\t\t\t\tclass=\"fancybox-iframe\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-color=\"#feae92\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:842px,695px,528px,352px;yo:459px,379px,287px,376px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:24,19,14,16;l:27,22,16,9;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:287px,237px,180px,108px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:hm-n-11;sp:1000;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bos:solid;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>WEITERE INFORMATIONEN \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-103-layer-123\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer fancybox-iframe\"\n\t\t\t\t\t\t\t\thref=\"#ninja-popup-4290\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:865px,714px,542px,372px;yo:495px,408px,309px,400px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap;s:30,24,18,21;l:27,22,16,17;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:140px,115px,87px,63px;h:41px,33px,25px,28px;\"\n\t\t\t\t\t\t\t\tdata-margin=\"t:15,12,9,6;r:10,8,6,4;b:15,12,9,6;l:10,8,6,4;\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:8,7,5,6;r:5,4,3,4;b:5,4,3,4;l:5,4,3,4;\"\n\t\t\t\t\t\t\t\tdata-border=\"bos:solid;boc:#5d0900;bow:1px,1px,1px,1px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"c:#fff;bgc:#d4b06d;boc:#dc0028;bos:solid;bow:0px,0px,0px,0px;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:11;font-family:'Circe';cursor:pointer;\"\n\t\t\t\t\t\t\t>KAUFEN \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-103-layer-137\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:665px,549px,417px,278px;yo:374px,308px,234px,258px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:154px,127px,96px,107px;h:176px,145px,110px,122px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:600;sp:600;sR:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7800;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:18;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"273\" height=\"312\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/hazelnut.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-103-layer-142\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:230px,189px,143px,17px;yo:74px,61px,46px,45px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:724px,597px,453px,462px;h:605px,499px,379px,386px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1038\" height=\"867\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/08\/CHOCO-Powder-Feather_on_red-3.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-103-layer-217\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:45px,37px,28px,26px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,33,25,22;l:45,37,28,30;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,148px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:14;font-family:'Circe';\"\n\t\t\t\t\t\t\t>HASELNUSS UND<br \/>\nMACADEMIA \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-103-layer-218\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:141px,116px,88px,118px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:24,19,14,14;l:24,19,14,16;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,149px;h:auto,auto,auto,36px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:15;font-family:'Circe';\"\n\t\t\t\t\t\t\t>MILCHSCHOKOLADE \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-103-layer-219\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,r;xo:-295px,-243px,-184px,330px;yo:172px,142px,107px,159px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:22,18,13,14;l:25,20,15,9;ls:1px,0px,0px,0px;a:center,center,center,right;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,auto,100px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8400;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:16;font-family:'FreeSerif';font-style:italic;\"\n\t\t\t\t\t\t\t>105 kcal \/ 26 g \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-103-layer-221\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,r;xo:757px,625px,474px,-5px;yo:80px,66px,50px,30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:182px,150px,113px,129px;h:166px,137px,104px,118px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:570;sp:600;sR:570;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7830;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"320\" height=\"292\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2021\/02\/cocoa.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-103-layer-222\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,8px;y:m;yo:-85px,-70px,-55px,-110px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:500px,412px,313px,313px;h:284px,234px,177px,178px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:openmodal;modal:hm-n-11;bg:rgba(0,0,0,0.5);spin:3;spinc:#ffffff;'\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"600\" height=\"341\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2023\/01\/Chocolate-Bars_NEW-3d-UK_MILK_HM-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t\t<rs-static-layers><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-1-layer-1\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer-static\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:r;xo:120px,99px,75px,0;y:m;yo:-90px,-90px,-70px,-115px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:57px,47px,46px,46px;h:62px,51px,50px,50px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:jumptoslide;slide:next;'\n\t\t\t\t\t\t\t\tdata-btrans=\"rY:180;\"\n\t\t\t\t\t\t\t\tdata-onslides=\"s:1;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;cursor:pointer;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"76\" height=\"83\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2020\/11\/arrow.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-1-layer-2\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer-static\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:120px,99px,75px,0;y:m;yo:-90px,-90px,-70px,-115px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:57px,47px,46px,46px;h:62px,51px,50px,50px;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:jumptoslide;slide:previous;'\n\t\t\t\t\t\t\t\tdata-onslides=\"s:1;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;cursor:pointer;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/chocolette.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"76\" height=\"83\" data-lazyload=\"\/\/chocolette.com\/wp-content\/uploads\/2020\/11\/arrow.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\t\t\t\t\t--><\/rs-static-layers>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_1_1',rl:[1240,1024,778,480],el:[880,800,760,760],gw:[1240,1024,778,480],gh:[880,800,760,760],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider11\"]!==undefined) {window.RS_MODULES.modules[\"revslider11\"].once = false;window.revapi1 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b960356 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"2b960356\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-377fd7b8\" data-id=\"377fd7b8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a7b8ad2 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"5a7b8ad2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-5c0704e3\" data-id=\"5c0704e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-1a0d8c3a\" data-id=\"1a0d8c3a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3763ee6c uael-video-gallery__column-1 uael-video-gallery-tablet__column-1 uael-video-gallery-mobile__column-1 elementor-widget elementor-widget-uael-video-gallery\" data-id=\"3763ee6c\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"video_slider\" data-widget_type=\"uael-video-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"uael-video-gallery-wrap uael-vg__layout-carousel uael-vg__action-inline uael-aspect-ratio-16_9\" data-action=\"inline\" data-layout=\"carousel\" data-all-filters=\"[&quot;filter-youtube&quot;]\" data-vg_slider=\"{&quot;slidesToShow&quot;:1,&quot;slidesToScroll&quot;:1,&quot;autoplaySpeed&quot;:5000,&quot;autoplay&quot;:false,&quot;infinite&quot;:true,&quot;pauseOnHover&quot;:false,&quot;speed&quot;:500,&quot;arrows&quot;:true,&quot;dots&quot;:false,&quot;rtl&quot;:false,&quot;prevArrow&quot;:&quot;&lt;button type=\\&quot;button\\&quot; data-role=\\&quot;none\\&quot; class=\\&quot;slick-prev\\&quot; aria-label=\\&quot;Previous\\&quot; tabindex=\\&quot;0\\&quot; role=\\&quot;button\\&quot;&gt;&lt;i class=\\&quot;fa fa-angle-left\\&quot;&gt;&lt;\\\/i&gt;&lt;\\\/button&gt;&quot;,&quot;nextArrow&quot;:&quot;&lt;button type=\\&quot;button\\&quot; data-role=\\&quot;none\\&quot; class=\\&quot;slick-next\\&quot; aria-label=\\&quot;Next\\&quot; tabindex=\\&quot;0\\&quot; role=\\&quot;button\\&quot;&gt;&lt;i class=\\&quot;fa fa-angle-right\\&quot;&gt;&lt;\\\/i&gt;&lt;\\\/button&gt;&quot;,&quot;responsive&quot;:[{&quot;breakpoint&quot;:1024,&quot;settings&quot;:{&quot;slidesToShow&quot;:1,&quot;slidesToScroll&quot;:1}},{&quot;breakpoint&quot;:767,&quot;settings&quot;:{&quot;slidesToShow&quot;:1,&quot;slidesToScroll&quot;:1}}]}\">\t\t\t\t<div class=\"uael-video__gallery-item\" id=\"uael-video__gallery-item1\">\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"uael-video__gallery-iframe\" style=\"background-image:url('https:\/\/i.ytimg.com\/vi\/vJugp2b0m4A\/maxresdefault.jpg');\">\n\t\t\t\t\t\t<a class=\"elementor-clickable uael-vg__play_full\" href=\"https:\/\/www.youtube.com\/watch?v=vJugp2b0m4A\" data-url=\"https:\/\/www.youtube.com\/embed\/vJugp2b0m4A?autoplay=1&amp;version=3&amp;enablejsapi=1\">\n\t\t\t\t\t\t\t<div class=\"uael-video__content-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"uael-video__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-vg__play\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-animation- uael-vg__play-icon\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"uael-vg__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-video__gallery-item\" id=\"uael-video__gallery-item2\">\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"uael-video__gallery-iframe\" style=\"background-image:url('https:\/\/i.ytimg.com\/vi\/vJugp2b0m4A\/maxresdefault.jpg');\">\n\t\t\t\t\t\t<a class=\"elementor-clickable uael-vg__play_full\" href=\"https:\/\/www.youtube.com\/watch?v=vJugp2b0m4A\" data-url=\"https:\/\/www.youtube.com\/embed\/vJugp2b0m4A?autoplay=1&amp;version=3&amp;enablejsapi=1\">\n\t\t\t\t\t\t\t<div class=\"uael-video__content-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"uael-video__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-vg__play\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-animation- uael-vg__play-icon\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"uael-vg__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-video__gallery-item\" id=\"uael-video__gallery-item3\">\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"uael-video__gallery-iframe\" style=\"background-image:url('https:\/\/i.ytimg.com\/vi\/vJugp2b0m4A\/maxresdefault.jpg');\">\n\t\t\t\t\t\t<a class=\"elementor-clickable uael-vg__play_full\" href=\"https:\/\/www.youtube.com\/watch?v=vJugp2b0m4A\" data-url=\"https:\/\/www.youtube.com\/embed\/vJugp2b0m4A?autoplay=1&amp;version=3&amp;enablejsapi=1\">\n\t\t\t\t\t\t\t<div class=\"uael-video__content-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"uael-video__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-vg__play\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-animation- uael-vg__play-icon\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"uael-vg__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\t\t<script type=\"text\/javascript\">\n\t\t\tjQuery( document ).ready( function( $ ) {\n\n\t\t\t\t$( '.uael-video-gallery-wrap' ).each( function() {\n\n\t\t\t\t\tvar $node_id \t= '3763ee6c';\n\t\t\t\t\tvar\tscope \t\t= $( '[data-id=\"' + $node_id + '\"]' );\n\t\t\t\t\tvar selector \t= $(this);\n\n\t\t\t\t\tif ( selector.closest( scope ).length < 1 ) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t}\n\n\t\t\t\t\tif ( ! selector.hasClass( 'uael-video-gallery-filter' ) ) {\n\t\t\t\t\t\treturn;\n\t\t\t\t\t}\n\n\t\t\t\t\tvar filters = scope.find( '.uael-video__gallery-filters' );\n\t\t\t\t\tvar def_cat = '*';\n\n\t\t\t\t\tif ( filters.length > 0 ) {\n\n\t\t\t\t\t\tvar def_filter = filters.data( 'default' );\n\n\t\t\t\t\t\tif ( '' !== def_filter ) {\n\n\t\t\t\t\t\t\tdef_cat \t= def_filter;\n\t\t\t\t\t\t\tdef_cat_sel = filters.find( '[data-filter=\"' + def_filter + '\"]' );\n\n\t\t\t\t\t\t\tif ( def_cat_sel.length > 0 ) {\n\t\t\t\t\t\t\t\tdef_cat_sel.siblings().removeClass( 'uael-filter__current' );\n\t\t\t\t\t\t\t\tdef_cat_sel.addClass( 'uael-filter__current' );\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t}\n\t\t\t\t\t}\n\n\t\t\t\t\tvar $obj = {};\n\n\t\t\t\t\tselector.imagesLoaded( function( e ) {\n\n\t\t\t\t\t\t$obj = selector.isotope({\n\t\t\t\t\t\t\tfilter: def_cat,\n\t\t\t\t\t\t\tlayoutMode: 'masonry',\n\t\t\t\t\t\t\titemSelector: '.uael-video__gallery-item',\n\t\t\t\t\t\t});\n\n\t\t\t\t\t\tselector.find( '.uael-video__gallery-item' ).resize( function() {\n\t\t\t\t\t\t\t$obj.isotope( 'layout' );\n\t\t\t\t\t\t});\n\t\t\t\t\t});\n\n\t\t\t\t});\n\t\t\t});\n\t\t<\/script>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-56f746a2\" data-id=\"56f746a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4268fae0 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"4268fae0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-386d4c5c\" data-id=\"386d4c5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-q_id=\"#about\" class=\"elementor-section elementor-top-section elementor-element elementor-element-28612ed elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"28612ed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-580a37f5\" data-id=\"580a37f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ec841c7 elementor-widget elementor-widget-image\" data-id=\"6ec841c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2020\/11\/heart.png\" title=\"Herz\" alt=\"Herz\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e5af88a elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"1e5af88a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-319cb728\" data-id=\"319cb728\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79f5c9fe elementor-widget elementor-widget-image\" data-id=\"79f5c9fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"63\" height=\"56\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/d.png\" class=\"attachment-full size-full wp-image-2276\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28728eaf free elementor-widget elementor-widget-text-editor\" data-id=\"28728eaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chocolette-Konditorei in Schweizer Besitz<br \/>wurde aus Leidenschaft geboren!<br \/>ROTE Schokolade ist ein unglaublich leckeres,<br \/>keine Schokolade mit Zuckerzusatz.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7ca1ac55\" data-id=\"7ca1ac55\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-684416ac elementor-widget elementor-widget-image\" data-id=\"684416ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"53\" height=\"88\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/g.png\" class=\"attachment-full size-full wp-image-2283\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63154e8a free elementor-widget elementor-widget-text-editor\" data-id=\"63154e8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Besitz von 10 globalen Patenten,<br \/>Unsere Fabrik basiert auf einem neuen technologischen<br \/>innovativer Stil, einige der beliebtesten zu produzieren<br \/>wollte Schokolade in der Welt.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-205c0567 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"205c0567\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-33ac5395\" data-id=\"33ac5395\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c90bf8c elementor-widget elementor-widget-image\" data-id=\"4c90bf8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"106\" height=\"73\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/f.png\" class=\"attachment-full size-full wp-image-2290\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c292b83 free elementor-widget elementor-widget-text-editor\" data-id=\"2c292b83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gebaut nach modernsten Spezifikationen f\u00fcr unseren Einsatz mit Wasser<br \/>und Luftreinigung, Wasserrecycling, freie K\u00fchlung<br \/>und Rekuperationstechnologien,<br \/>unser Ziel ist es, mit uns die Erde gl\u00fccklich zu machen<br \/>(wir wissen, dass Sie von ROT begeistert sein werden)!<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-375802f5\" data-id=\"375802f5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b6c1ee9 elementor-widget elementor-widget-image\" data-id=\"7b6c1ee9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"50\" height=\"72\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/l.png\" class=\"attachment-full size-full wp-image-2297\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f35235a free elementor-widget elementor-widget-text-editor\" data-id=\"1f35235a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die ma\u00dfgeschneiderte Ausr\u00fcstung wurde von f\u00fchrenden<br \/>Deutsche und Schweizer Hersteller.<br \/>Diese patentierte einzigartige Ausr\u00fcstung erm\u00f6glicht<br \/>uns, ROTE Schokolade mit weniger Kalorien herzustellen,<br \/>weniger Fett und kein Zuckerzusatz<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2df72906 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"2df72906\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41e7a58c elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"41e7a58c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-478bde9 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"478bde9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-449c8806\" data-id=\"449c8806\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4bf09550 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"4bf09550\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66a5c016\" data-id=\"66a5c016\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4dab3381 elementor-widget elementor-widget-heading\" data-id=\"4dab3381\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-xxl\">Nehmen Sie uns nicht beim Wort\u2026<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dcebcf3 elementor-widget elementor-widget-heading\" data-id=\"1dcebcf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Hier sind nur einige weitere Gr\u00fcnde, uns zu vertrauen und zu lieben!<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-524ca2b elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"524ca2b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2256d1a\" data-id=\"2256d1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d123624 elementor-widget elementor-widget-image\" data-id=\"d123624\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/01\/klbd.png\" title=\"klbd\" alt=\"klbd\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1b4c3b2a\" data-id=\"1b4c3b2a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3706655b elementor-widget elementor-widget-image\" data-id=\"3706655b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/01\/brgs.png\" title=\"brgs\" alt=\"brgs\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-21e3c6b3\" data-id=\"21e3c6b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2096a85 elementor-widget elementor-widget-image\" data-id=\"2096a85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/01\/gfree.png\" title=\"gfree\" alt=\"gfree\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11ac80dc elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"11ac80dc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-5b641048\" data-id=\"5b641048\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-41eadec7\" data-id=\"41eadec7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21a2a2ba elementor-widget elementor-widget-video\" data-id=\"21a2a2ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/RQfYbkRgbW4&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-6620e8c5\" data-id=\"6620e8c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a9f89a0 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"3a9f89a0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23b2f068\" data-id=\"23b2f068\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-q_id=\"#contact\" class=\"elementor-section elementor-top-section elementor-element elementor-element-43a8bbcc elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"43a8bbcc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-591fcefa\" data-id=\"591fcefa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3ebc2d7a elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"3ebc2d7a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6d97448e\" data-id=\"6d97448e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5da88a58 elementor-widget elementor-widget-text-editor\" data-id=\"5da88a58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>B\u00fcro<\/strong><br \/> Chocolette SA Rue Adrien-Lachel 26,<br \/>Genf, CH 1207, Schweiz<br \/>E: info@chocolette.com<\/p>\n<\/p>\n<p><strong>B\u00fcro &amp; Schokoladenfabrik Lettland<\/strong><br \/>Schokoladen-Konfekt SIA<br \/>Aviacijas 18, Jelgava, LV-3004<br \/>T: +371 661 40 700<br \/>E: info@chocolette.com<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-3898d83f\" data-id=\"3898d83f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2739e912 elementor-widget elementor-widget-heading\" data-id=\"2739e912\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><strong>Ihre Nachricht<\/strong><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-764e49b0 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"764e49b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;button_width&quot;:&quot;20&quot;,&quot;step_next_label&quot;:&quot;N\\u00e4chste&quot;,&quot;step_previous_label&quot;:&quot;Bisherige&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Kontakt\" aria-label=\"Kontakt\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"2743\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"764e49b0\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"RED Chocolette\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Name\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-tel elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-tel\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tTel\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[tel]\" id=\"form-field-tel\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"T:\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Nur Nummern oder Telefon-Zeichen (#, -, *, etc) werden akzeptiert.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Geben sie ihre E-Mailadresse ein\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-text elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-text\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tBotschaft\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-xs\" name=\"form_fields[text]\" id=\"form-field-text\" rows=\"4\" placeholder=\"Text\" required=\"required\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text\">\n\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_aa75486]\" id=\"form-field-field_aa75486\" class=\"elementor-field elementor-size-xs \" style=\"display:none !important;\">\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-20 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-xs\" type=\"submit\" id=\"form_button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Okay&gt;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-642b2138 elementor-section-height-min-height elementor-section-full_width elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no qode-content-aligment-left\" data-id=\"642b2138\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-485ce8d9\" data-id=\"485ce8d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>DER ERSTEINDIE WELT ROTE Schokoriegel wurden nachdenklich gemacht entwickelt, um Ihre Geschmacksknospen zu verbessern, damit Sie es k\u00f6nnen Genie\u00dfen Sie den Geschmack bei jedem Bissen. LECKER&amp;HELL Kreiert von Meister-Chocolatiers aus Frankreich und der Schweiz schafft unser einzigartiger, patentierter Stil eine wohlschmeckende Schokolade ohne Zuckerzusatz und&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"footnotes":""},"class_list":["post-2743","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>haupts\u00e4chlich - RED Chocolette<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chocolette.com\/de\/hauptsaechlich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"haupts\u00e4chlich - RED Chocolette\" \/>\n<meta property=\"og:description\" content=\"DER ERSTEINDIE WELT ROTE Schokoriegel wurden nachdenklich gemacht entwickelt, um Ihre Geschmacksknospen zu verbessern, damit Sie es k\u00f6nnen Genie\u00dfen Sie den Geschmack bei jedem Bissen. LECKER&amp;HELL Kreiert von Meister-Chocolatiers aus Frankreich und der Schweiz schafft unser einzigartiger, patentierter Stil eine wohlschmeckende Schokolade ohne Zuckerzusatz und...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chocolette.com\/de\/hauptsaechlich\/\" \/>\n<meta property=\"og:site_name\" content=\"RED Chocolette\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T13:34:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/almond.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"haupts\u00e4chlich - RED Chocolette","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chocolette.com\/de\/hauptsaechlich\/","og_locale":"de_DE","og_type":"article","og_title":"haupts\u00e4chlich - RED Chocolette","og_description":"DER ERSTEINDIE WELT ROTE Schokoriegel wurden nachdenklich gemacht entwickelt, um Ihre Geschmacksknospen zu verbessern, damit Sie es k\u00f6nnen Genie\u00dfen Sie den Geschmack bei jedem Bissen. LECKER&amp;HELL Kreiert von Meister-Chocolatiers aus Frankreich und der Schweiz schafft unser einzigartiger, patentierter Stil eine wohlschmeckende Schokolade ohne Zuckerzusatz und...","og_url":"https:\/\/chocolette.com\/de\/hauptsaechlich\/","og_site_name":"RED Chocolette","article_modified_time":"2026-04-10T13:34:55+00:00","og_image":[{"url":"https:\/\/chocolette.com\/wp-content\/uploads\/2021\/03\/almond.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/chocolette.com\/de\/hauptsaechlich\/","url":"https:\/\/chocolette.com\/de\/hauptsaechlich\/","name":"haupts\u00e4chlich - RED Chocolette","isPartOf":{"@id":"https:\/\/chocolette.com\/de\/#website"},"datePublished":"2021-11-01T12:30:02+00:00","dateModified":"2026-04-10T13:34:55+00:00","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chocolette.com\/de\/hauptsaechlich\/"]}]},{"@type":"WebSite","@id":"https:\/\/chocolette.com\/de\/#website","url":"https:\/\/chocolette.com\/de\/","name":"RED Chocolette","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chocolette.com\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/chocolette.com\/de\/wp-json\/wp\/v2\/pages\/2743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chocolette.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/chocolette.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/chocolette.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chocolette.com\/de\/wp-json\/wp\/v2\/comments?post=2743"}],"version-history":[{"count":1,"href":"https:\/\/chocolette.com\/de\/wp-json\/wp\/v2\/pages\/2743\/revisions"}],"predecessor-version":[{"id":2745,"href":"https:\/\/chocolette.com\/de\/wp-json\/wp\/v2\/pages\/2743\/revisions\/2745"}],"wp:attachment":[{"href":"https:\/\/chocolette.com\/de\/wp-json\/wp\/v2\/media?parent=2743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}